{"id":5812,"date":"2021-05-03T15:54:38","date_gmt":"2021-05-03T13:54:38","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5812"},"modified":"2021-05-03T15:54:38","modified_gmt":"2021-05-03T13:54:38","slug":"nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/","title":{"rendered":"Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">L<\/span>a nomina del Presidente del Comitato d&#8217;Indirizzo della Fondazione Valenzi <strong>Roberto Race<\/strong> a Cavaliere al Merito della Repubblica Italiana \u00e8 un riconoscimento importante per tutti noi.&#8221;<\/p>\n<p>Lo dichiara la Presidente della Fondazione Valenzi <strong>Lucia Valenzi<\/strong> nel commentare le nuove onorificenze al Merito della Repubblica Italiana apparse sul sito della Presidenza della Repubblica.<\/p>\n<p>&#8220;Viene premiato, insieme ai meriti professionali, l&#8217;impegno della Fondazione per il sociale e la collettivit\u00e0. Un percorso che la Fondazione ha iniziato con Race Segretario Generale nel 2009 e che ci ha visto realizzare in questi 12 anni un punto di riferimento per un libero e sereno dialogo su temi riguardanti la memoria e l&#8217;attualit\u00e0, con almeno 350 eventi nel campo della cultura e dell&#8217;arte e 30.000 presenze, coinvolgendo in progetti educativi 10.000 studenti di ogni ordine e grado.\u201d<\/p>\n<p>L&#8217;onorificenza si aggiunge a quella della Presidente del Comitato Scientifico <strong>Lida Viganoni<\/strong>, insignita dal Presidente Napolitano come Grande Ufficiale Ordine al Merito della Repubblica Italiana nel 2013.<\/p>\n<p>\u201cVoglio congratularmi anche con altri campani che hanno ricevuto le onorificenze. Con i neo Cavaliere come il Commissario Consob <strong>Giuseppe Maria Berruti<\/strong>, la giornalista e conduttrice dell\u2019<em>Aria che tira<\/em> a LA7 \u00a0<strong>Myrta Merlino<\/strong> e con il vicedirettore de Il Corriere della Sera <strong>Venanzio Postiglione <\/strong>e il docente di tecnica delle Costruzioni della Federico II<strong> Edoardo Cosenza<\/strong>\u00a0che hanno ricevuto quella di Ufficiale.<\/p>\n<p><span style=\"font-family: garamond, times new roman, serif;\">\u201cVoglio anche congratularmi- conclude Lucia Valenzi- con i neo Commendatore come il questore di Venezia <strong>Maurizio Masciopinto<\/strong>, per anni impegnato nella lotta alla criminalit\u00e0 a Napoli, con il capo del Cerimoniale di Stato alla Presidenza del Consiglio <strong>Enrico Passaro<\/strong> e gli ex rettori dell&#8217;Universit\u00e0 napoletane, dell&#8217;Orientale <strong>Elda Morlicchio<\/strong> e della Federico II <strong>Guido Trombetti<\/strong>, con i neo\u00a0Cavaliere di Gran Croce come il presidente del Conservatorio di San Pietro a Majella <strong>Luigi Carbone<\/strong>, il giurista <strong>Luigi Labruna<\/strong> e l&#8217;ex prefetto di Napoli <strong>Gerarda Pantalone<\/strong>&#8220;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nomina del Presidente del Comitato d&#8217;Indirizzo della Fondazione Valenzi Roberto Race a Cavaliere al Merito della Repubblica Italiana \u00e8 un riconoscimento importante per tutti noi.&#8221; Lo dichiara la Presidente della Fondazione Valenzi Lucia Valenzi nel commentare le nuove onorificenze al Merito della Repubblica Italiana apparse sul sito della Presidenza della Repubblica. &#8220;Viene premiato, insieme [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5813,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi -\" \/>\n<meta property=\"og:description\" content=\"La nomina del Presidente del Comitato d&#8217;Indirizzo della Fondazione Valenzi Roberto Race a Cavaliere al Merito della Repubblica Italiana \u00e8 un riconoscimento importante per tutti noi.&#8221; Lo dichiara la Presidente della Fondazione Valenzi Lucia Valenzi nel commentare le nuove onorificenze al Merito della Repubblica Italiana apparse sul sito della Presidenza della Repubblica. &#8220;Viene premiato, insieme [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-03T13:54:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/05\/2009-Il-Presidente-Giorgio-Napolitano-con-Lucia-Valenzi-Presidente-della-Fondazione-Valenzi-e-Roberto-Race-Segretario-Generale-della-Fondazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2293\" \/>\n\t<meta property=\"og:image:height\" content=\"1598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/\",\"name\":\"Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/05\/2009-Il-Presidente-Giorgio-Napolitano-con-Lucia-Valenzi-Presidente-della-Fondazione-Valenzi-e-Roberto-Race-Segretario-Generale-della-Fondazione.jpg\",\"datePublished\":\"2021-05-03T13:54:38+00:00\",\"dateModified\":\"2021-05-03T13:54:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/05\/2009-Il-Presidente-Giorgio-Napolitano-con-Lucia-Valenzi-Presidente-della-Fondazione-Valenzi-e-Roberto-Race-Segretario-Generale-della-Fondazione.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/05\/2009-Il-Presidente-Giorgio-Napolitano-con-Lucia-Valenzi-Presidente-della-Fondazione-Valenzi-e-Roberto-Race-Segretario-Generale-della-Fondazione.jpg\",\"width\":2293,\"height\":1598,\"caption\":\"Napoli-Il Presidente della Repubblica Giorgio Napolitano con la moglie Clio e la Signora Valenzi durante l'incontro in Prefettura.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/","og_locale":"it_IT","og_type":"article","og_title":"Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi -","og_description":"La nomina del Presidente del Comitato d&#8217;Indirizzo della Fondazione Valenzi Roberto Race a Cavaliere al Merito della Repubblica Italiana \u00e8 un riconoscimento importante per tutti noi.&#8221; Lo dichiara la Presidente della Fondazione Valenzi Lucia Valenzi nel commentare le nuove onorificenze al Merito della Repubblica Italiana apparse sul sito della Presidenza della Repubblica. &#8220;Viene premiato, insieme [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-05-03T13:54:38+00:00","og_image":[{"width":2293,"height":1598,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/05\/2009-Il-Presidente-Giorgio-Napolitano-con-Lucia-Valenzi-Presidente-della-Fondazione-Valenzi-e-Roberto-Race-Segretario-Generale-della-Fondazione.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/","name":"Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/05\/2009-Il-Presidente-Giorgio-Napolitano-con-Lucia-Valenzi-Presidente-della-Fondazione-Valenzi-e-Roberto-Race-Segretario-Generale-della-Fondazione.jpg","datePublished":"2021-05-03T13:54:38+00:00","dateModified":"2021-05-03T13:54:38+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/05\/2009-Il-Presidente-Giorgio-Napolitano-con-Lucia-Valenzi-Presidente-della-Fondazione-Valenzi-e-Roberto-Race-Segretario-Generale-della-Fondazione.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/05\/2009-Il-Presidente-Giorgio-Napolitano-con-Lucia-Valenzi-Presidente-della-Fondazione-Valenzi-e-Roberto-Race-Segretario-Generale-della-Fondazione.jpg","width":2293,"height":1598,"caption":"Napoli-Il Presidente della Repubblica Giorgio Napolitano con la moglie Clio e la Signora Valenzi durante l'incontro in Prefettura."},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/nomina-race-a-cavaliere-al-merito-della-repubblica-italiana-fondazione-valenzi-importante-riconoscimento-per-tutti-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Nomina Race a Cavaliere al Merito della Repubblica Italiana, Fondazione Valenzi: importante riconoscimento per tutti noi"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5812"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5812"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5812\/revisions"}],"predecessor-version":[{"id":5814,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5812\/revisions\/5814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5813"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}