{"id":5907,"date":"2021-05-20T21:53:30","date_gmt":"2021-05-20T19:53:30","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5907"},"modified":"2021-05-20T21:53:30","modified_gmt":"2021-05-20T19:53:30","slug":"sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/","title":{"rendered":"Sostegni bis, Confesercenti: &#8220;Bene su turismo, lavoro e sostegno ai costi delle imprese&#8221;"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">F<\/span>ra i provvedimenti varati per venire incontro alle esigenze dell\u2019economia, il\u00a0Sostegni Bis\u00a0\u00e8 quello meglio strutturato: stando alle anticipazioni, il testo\u00a0recepisce molte delle nostre proposte, e costituisce senz\u2019altro un passo avanti sul fronte del turismo, della tutela del lavoro e del sostegno dei costi delle imprese. Sugli indennizzi, per\u00f2, si poteva fare di pi\u00f9, anche in considerazione della durata pi\u00f9 lunga del previsto delle restrizioni. Sar\u00e0 fondamentale, inoltre, garantire un accesso rapido e \u2018sburocratizzato\u2019 ai benefici, dai ristori ai crediti di imposta.<\/p>\n<p>Cos\u00ec afferma Confesercenti.<\/p>\n<p>Sebbene siano state incrementate, infatti, le risorse per i contributi a fondo perduto rischiano ancora una volta di trasformarsi in importi insoddisfacenti per le singole imprese, visto che si \u00e8 allargata anche la platea dei beneficiari. Sebbene sia una novit\u00e0 importante e potenzialmente molto utile, sono insufficienti pure le risorse assegnate al Fondo per il sostegno delle imprese costrette a rimanere chiuse: 100 milioni di euro non bastano a coprire le esigenze di discoteche, palestre, piscine, sale scommesse e delle altre attivit\u00e0 che non ripartiranno a breve. Un problema da valutare con attenzione: la pandemia ha gi\u00e0 cancellato oltre 40 miliardi di reddito degli autonomi nel solo 2020, un bilancio peggiorato ulteriormente in questi primi 5 mesi del 2021, trascorsi sotto il segno delle restrizioni.<\/p>\n<p>&nbsp;<\/p>\n<p>Siamo soddisfatti, invece, che il governo abbia fatto propria la nostra richiesta di affrontare di petto il tema dei costi sostenuti dalle imprese: in particolare, apprezziamo l\u2019estensione del credito di imposta per le locazioni, la reintroduzione di quello per le sanificazioni e la creazione di un fondo per il pagamento delle tariffe sui rifiuti, cos\u00ec come le decontribuzioni e le risorse in pi\u00f9 riservate al turismo. Positivo, inoltre, che si sia evitata, in zona Cesarini, una stretta eccessiva su credito e garanzie, anche se per facilitare l\u2019accesso al credito delle PMI \u00e8 necessario procedere anche al rifinanziamento del sistema dei Confidi.<\/p>\n<p>&nbsp;<\/p>\n<p>Serve, poi, una strategia per la ripresa dei consumi ed il riequilibrio della concorrenza nel commercio: sempre nel 2020 la pandemia ha bruciato 123 miliardi di spesa, circa 5mila euro a famiglia, con perdite ingentissime non solo per alberghi e pubblici esercizi \u2013 che hanno visto sparire lo scorso anno oltre 40 miliardi \u2013 ma anche per il commercio di prossimit\u00e0: il comparto moda ha perso nell\u2019anno della pandemia oltre 36 milioni di euro al giorno di vendite, parte delle quali \u00e8 stata assorbita dall\u2019online, che ha potuto operare anche quando i negozi \u2018fisici\u2019 erano chiusi per decreto. Servono dunque misure mirate per correggere le distorsioni concorrenziali tra i canali di vendita e per sostenere il rilancio della spesa delle famiglie.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fra i provvedimenti varati per venire incontro alle esigenze dell\u2019economia, il\u00a0Sostegni Bis\u00a0\u00e8 quello meglio strutturato: stando alle anticipazioni, il testo\u00a0recepisce molte delle nostre proposte, e costituisce senz\u2019altro un passo avanti sul fronte del turismo, della tutela del lavoro e del sostegno dei costi delle imprese. Sugli indennizzi, per\u00f2, si poteva fare di pi\u00f9, anche in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4533,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sostegni bis, Confesercenti: &quot;Bene su turismo, lavoro e sostegno ai costi delle imprese&quot; -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sostegni bis, Confesercenti: &quot;Bene su turismo, lavoro e sostegno ai costi delle imprese&quot; -\" \/>\n<meta property=\"og:description\" content=\"Fra i provvedimenti varati per venire incontro alle esigenze dell\u2019economia, il\u00a0Sostegni Bis\u00a0\u00e8 quello meglio strutturato: stando alle anticipazioni, il testo\u00a0recepisce molte delle nostre proposte, e costituisce senz\u2019altro un passo avanti sul fronte del turismo, della tutela del lavoro e del sostegno dei costi delle imprese. Sugli indennizzi, per\u00f2, si poteva fare di pi\u00f9, anche in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-20T19:53:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-02-alle-16.10.44.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/\",\"name\":\"Sostegni bis, Confesercenti: \\\"Bene su turismo, lavoro e sostegno ai costi delle imprese\\\" -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-02-alle-16.10.44.png\",\"datePublished\":\"2021-05-20T19:53:30+00:00\",\"dateModified\":\"2021-05-20T19:53:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-02-alle-16.10.44.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-02-alle-16.10.44.png\",\"width\":1160,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sostegni bis, Confesercenti: &#8220;Bene su turismo, lavoro e sostegno ai costi delle imprese&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sostegni bis, Confesercenti: \"Bene su turismo, lavoro e sostegno ai costi delle imprese\" -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/","og_locale":"it_IT","og_type":"article","og_title":"Sostegni bis, Confesercenti: \"Bene su turismo, lavoro e sostegno ai costi delle imprese\" -","og_description":"Fra i provvedimenti varati per venire incontro alle esigenze dell\u2019economia, il\u00a0Sostegni Bis\u00a0\u00e8 quello meglio strutturato: stando alle anticipazioni, il testo\u00a0recepisce molte delle nostre proposte, e costituisce senz\u2019altro un passo avanti sul fronte del turismo, della tutela del lavoro e del sostegno dei costi delle imprese. Sugli indennizzi, per\u00f2, si poteva fare di pi\u00f9, anche in [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-05-20T19:53:30+00:00","og_image":[{"width":1160,"height":786,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-02-alle-16.10.44.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/","name":"Sostegni bis, Confesercenti: \"Bene su turismo, lavoro e sostegno ai costi delle imprese\" -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-02-alle-16.10.44.png","datePublished":"2021-05-20T19:53:30+00:00","dateModified":"2021-05-20T19:53:30+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-02-alle-16.10.44.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2020\/11\/Schermata-2020-11-02-alle-16.10.44.png","width":1160,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sostegni-bis-confesercenti-bene-su-turismo-lavoro-e-sostegno-ai-costi-delle-imprese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Sostegni bis, Confesercenti: &#8220;Bene su turismo, lavoro e sostegno ai costi delle imprese&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5907"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5907"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5907\/revisions"}],"predecessor-version":[{"id":5908,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5907\/revisions\/5908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/4533"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}