{"id":5933,"date":"2021-05-24T17:26:37","date_gmt":"2021-05-24T15:26:37","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5933"},"modified":"2021-05-24T17:26:37","modified_gmt":"2021-05-24T15:26:37","slug":"pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/","title":{"rendered":"Pac, Cia: giungere ad accordo su riforma entro fine maggio"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">S<\/span>i apre una settimana decisiva per il futuro dell\u2019agricoltura Ue, con i triloghi del 25, 26 e 27 maggio a Bruxelles che potrebbero segnare finalmente l\u2019accordo politico sulla riforma della Pac.<\/p>\n<p>Cos\u00ec Cia-Agricoltori Italiani, che auspica il raggiungimento dell\u2019intesa nei prossimi giorni, per far s\u00ec che gli agricoltori europei possano contare su una legislazione certa, equilibrata, innovativa, capace di garantire insieme la competitivit\u00e0 e la sostenibilit\u00e0 del settore.<\/p>\n<p>La Pac \u00e8, e deve rimanere, la politica degli agricoltori e per gli agricoltori -ricorda l\u2019organizzazione- capace di generare esternalit\u00e0 positive per la collettivit\u00e0 e per lo sviluppo delle aree rurali. Il progetto Cia \u201cIl Paese che Vogliamo\u201d passa anche attraverso la nuova Pac che, insieme a un uso efficiente e strategico delle risorse del Piano Nazionale di Ripresa e Resilienza, pu\u00f2 essere in grado di far ripartire l\u2019economia del Paese con l\u2019agricoltura protagonista.<\/p>\n<p>E\u2019 chiaro che ci sono ancora nodi importanti da sciogliere -sottolinea Cia-. Questi, infatti, saranno giorni determinanti per fare in modo che tutti gli strumenti in discussione siano adeguati alle sfide dei prossimi anni, dai cambiamenti climatici al Green Deal. La proposta di riforma, iniziata nel 2018, ha subito diversi aggiustamenti, anche nei mesi scorsi, proprio per rispondere a una nuova visione di ripresa e sviluppo, generata dalla pandemia, e per raggiungere obiettivi di sostenibilit\u00e0 sempre pi\u00f9 ambiziosi.<\/p>\n<p>Per Cia, serve un accordo sulla nuova Pac che consenta una redistribuzione pi\u00f9 equa delle risorse, cos\u00ec come un\u2019attenzione alle politiche ambientali, con l\u2019agricoltura al centro, incentivando comportamenti virtuosi. Gli agricoltori europei sono pronti a fare la propria parte per diventare sempre pi\u00f9 sostenibili, quindi s\u00ec a una Pac 2023-2027 \u201cverde\u201d, ma senza dimenticare mai che si tratta di una politica economica che, storicamente, esiste per sostenere il reddito degli agricoltori e assicurare l\u2019approvvigionamento alimentare.<\/p>\n<p>\u201cL\u2019Italia sar\u00e0 sicuramente impegnata affinch\u00e9 nell\u2019accordo siano rispecchiate tutte le specificit\u00e0 e le esigenze dei nostri territori -dichiara il presidente Dino Scanavino-. Come Cia, ci siamo e lavoreremo perch\u00e9 l\u2019agricoltura diventi, sempre di pi\u00f9, un settore strategico per il nostro Paese e per l\u2019Europa\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si apre una settimana decisiva per il futuro dell\u2019agricoltura Ue, con i triloghi del 25, 26 e 27 maggio a Bruxelles che potrebbero segnare finalmente l\u2019accordo politico sulla riforma della Pac. Cos\u00ec Cia-Agricoltori Italiani, che auspica il raggiungimento dell\u2019intesa nei prossimi giorni, per far s\u00ec che gli agricoltori europei possano contare su una legislazione certa, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":194,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[537,56],"tags":[1724,367,1362],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pac, Cia: giungere ad accordo su riforma entro fine maggio -<\/title>\n<meta name=\"description\" content=\"Si apre una settimana decisiva per il futuro dell\u2019agricoltura Ue, con i triloghi del 25, 26 e 27 maggio a Bruxelles che potrebbero segnare\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pac, Cia: giungere ad accordo su riforma entro fine maggio -\" \/>\n<meta property=\"og:description\" content=\"Si apre una settimana decisiva per il futuro dell\u2019agricoltura Ue, con i triloghi del 25, 26 e 27 maggio a Bruxelles che potrebbero segnare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-24T15:26:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/\",\"name\":\"Pac, Cia: giungere ad accordo su riforma entro fine maggio -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg\",\"datePublished\":\"2021-05-24T15:26:37+00:00\",\"dateModified\":\"2021-05-24T15:26:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"description\":\"Si apre una settimana decisiva per il futuro dell\u2019agricoltura Ue, con i triloghi del 25, 26 e 27 maggio a Bruxelles che potrebbero segnare\",\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg\",\"width\":960,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pac, Cia: giungere ad accordo su riforma entro fine maggio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pac, Cia: giungere ad accordo su riforma entro fine maggio -","description":"Si apre una settimana decisiva per il futuro dell\u2019agricoltura Ue, con i triloghi del 25, 26 e 27 maggio a Bruxelles che potrebbero segnare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/","og_locale":"it_IT","og_type":"article","og_title":"Pac, Cia: giungere ad accordo su riforma entro fine maggio -","og_description":"Si apre una settimana decisiva per il futuro dell\u2019agricoltura Ue, con i triloghi del 25, 26 e 27 maggio a Bruxelles che potrebbero segnare","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-05-24T15:26:37+00:00","og_image":[{"width":960,"height":625,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/","name":"Pac, Cia: giungere ad accordo su riforma entro fine maggio -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg","datePublished":"2021-05-24T15:26:37+00:00","dateModified":"2021-05-24T15:26:37+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"description":"Si apre una settimana decisiva per il futuro dell\u2019agricoltura Ue, con i triloghi del 25, 26 e 27 maggio a Bruxelles che potrebbero segnare","breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/agricoltura.jpg","width":960,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/pac-cia-giungere-ad-accordo-su-riforma-entro-fine-maggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Pac, Cia: giungere ad accordo su riforma entro fine maggio"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5933"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5933"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5933\/revisions"}],"predecessor-version":[{"id":5934,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5933\/revisions\/5934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/194"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}