{"id":5948,"date":"2021-05-30T21:04:16","date_gmt":"2021-05-30T19:04:16","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5948"},"modified":"2021-05-30T21:04:16","modified_gmt":"2021-05-30T19:04:16","slug":"ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/","title":{"rendered":"Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">C<\/span>ome sta avvenendo per il vaccino anti-Covid, l\u2019Ue rischia il sorpasso da Londra sul fronte delle biotecnologie e dell\u2019ingegneria genetica. Dopo l\u2019avvio delle consultazioni sull\u2019autorizzo del genome editing, la Gran Bretagna post-Brexit prende le distanze dalle politiche comunitarie sulle innovazioni genetiche, equiparate agli Ogm da una sentenza della Corte di giustizia europea nel 2018.<\/p>\n<p>Cia-Agricoltori Italiani esprime la sua preoccupazione e chiede a Bruxelles la revisione di una legislazione ormai obsoleta, che non consente una transizione green in agricoltura, vietando quelle biotecnologie -premiate nel 2020 col Nobel della chimica- che consentono al settore di affrontare con tempestivit\u00e0 le sfide della competitivit\u00e0 del mercato globale e di realizzare gli obiettivi di sostenibilit\u00e0 tracciati dal Green Deal.<\/p>\n<p>\u201cIl genome editing \u2013dichiara il presidente Cia, Dino Scanavino- non presuppone inserimento di Dna estraneo mediante geni provenienti da altre specie. Si opera, infatti, internamente al Dna della pianta, che rimane immutato e assicura la continuit\u00e0 delle caratteristiche dei nostri prodotti, garantendo anche l&#8217;aumento delle rese, insieme alla riduzione dell&#8217;impatto dei prodotti chimici e al risparmio di risorse idriche\u201d.<\/p>\n<p>Le nuove biotecnologie arrivano a perfezionare il corredo genetico delle piante in maniera simile a quanto avviene in natura, ma con maggior precisione e rapidit\u00e0, oltre ad avere il vantaggio di essere poco costose e di potersi facilmente adattare alle tante tipicit\u00e0 dei nostri territori. \u201cL\u2019agricoltura non pu\u00f2 fare a meno del miglioramento genetico, che ha da sempre accompagnato la sua storia mediante le tecniche tradizionali di incrocio e innovazione varietale \u2013ha spiegato Scanavino-. <strong>Oggi abbiamo bisogno di ulteriore miglioramento per adattare le nostre colture a un contesto ambientale trasformato dal cambiamento climatico e minacciato dalla Xylella e dai patogeni fungini che attaccano la vite<\/strong>\u201d.<\/p>\n<p>\u201cUn ultimo aspetto, riguarda la gestione di queste innovazioni \u2013conclude Scanavino-. Non possiamo permetterci che il miglioramento genetico sia gestito solo da multinazionali lontane dalle esigenze reali del mondo agricolo. Dobbiamo, dunque, promuovere tutti gli strumenti che possano sviluppare nuove relazioni tra pubblico e privato e interazioni pi\u00f9 strette tra mondo dell\u2019impresa e mondo della ricerca\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come sta avvenendo per il vaccino anti-Covid, l\u2019Ue rischia il sorpasso da Londra sul fronte delle biotecnologie e dell\u2019ingegneria genetica. Dopo l\u2019avvio delle consultazioni sull\u2019autorizzo del genome editing, la Gran Bretagna post-Brexit prende le distanze dalle politiche comunitarie sulle innovazioni genetiche, equiparate agli Ogm da una sentenza della Corte di giustizia europea nel 2018. Cia-Agricoltori [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":500,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[1728,118],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green -\" \/>\n<meta property=\"og:description\" content=\"Come sta avvenendo per il vaccino anti-Covid, l\u2019Ue rischia il sorpasso da Londra sul fronte delle biotecnologie e dell\u2019ingegneria genetica. Dopo l\u2019avvio delle consultazioni sull\u2019autorizzo del genome editing, la Gran Bretagna post-Brexit prende le distanze dalle politiche comunitarie sulle innovazioni genetiche, equiparate agli Ogm da una sentenza della Corte di giustizia europea nel 2018. Cia-Agricoltori [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-30T19:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/agricoltura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"637\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/\",\"name\":\"Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/agricoltura.jpg\",\"datePublished\":\"2021-05-30T19:04:16+00:00\",\"dateModified\":\"2021-05-30T19:04:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/agricoltura.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/agricoltura.jpg\",\"width\":960,\"height\":637},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/","og_locale":"it_IT","og_type":"article","og_title":"Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green -","og_description":"Come sta avvenendo per il vaccino anti-Covid, l\u2019Ue rischia il sorpasso da Londra sul fronte delle biotecnologie e dell\u2019ingegneria genetica. Dopo l\u2019avvio delle consultazioni sull\u2019autorizzo del genome editing, la Gran Bretagna post-Brexit prende le distanze dalle politiche comunitarie sulle innovazioni genetiche, equiparate agli Ogm da una sentenza della Corte di giustizia europea nel 2018. Cia-Agricoltori [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-05-30T19:04:16+00:00","og_image":[{"width":960,"height":637,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/agricoltura.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/","name":"Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/agricoltura.jpg","datePublished":"2021-05-30T19:04:16+00:00","dateModified":"2021-05-30T19:04:16+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/agricoltura.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/agricoltura.jpg","width":960,"height":637},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/ue-cia-rischio-sorpasso-da-uk-su-genome-editing-indispensabile-per-transizione-green\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Ue, Cia: rischio sorpasso da Uk su genome editing indispensabile per transizione green"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5948"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5948"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5948\/revisions"}],"predecessor-version":[{"id":5949,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5948\/revisions\/5949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/500"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}