{"id":5972,"date":"2021-06-07T11:02:51","date_gmt":"2021-06-07T09:02:51","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5972"},"modified":"2021-06-07T11:02:51","modified_gmt":"2021-06-07T09:02:51","slug":"obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/","title":{"rendered":"Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d&#8217;Italia"},"content":{"rendered":"<p><strong><span class=\"dropcap dropcap3\">A<\/span>l via dal 5 giugno \u201cObiettivo Terra\u201d 2022<\/strong>, <em>la nuova edizione del concorso di fotografia geografico-ambientale promosso da <strong>Fondazione UniVerde<\/strong> e <strong>Societ\u00e0 Geografica Italiana Onlus<\/strong>, dedicato alla difesa e alla valorizzazione del patrimonio ambientale, del paesaggio, dei borghi, delle peculiarit\u00e0 e delle tradizioni enogastronomiche, agricole, artigianali, storico-culturali e sociali dei <strong>Parchi Nazionali, Regionali<\/strong>,<strong> Interregionali<\/strong>, delle<strong> Aree Marine Protette<\/strong>, delle<strong> Riserve Statal<\/strong>i e <strong>Regionali<\/strong>. Obiettivo del contest \u00e8 quello di promuovere la diffusione di un modello di turismo ecosostenibile e responsabile. <\/em><\/p>\n<p><em>La cerimonia di premiazione del concorso si terr\u00e0 il 22 aprile 2022 per celebrare la <\/em><strong>52a Giornata Mondiale della Terra<\/strong><em>. <\/em>\u201cObiettivo Terra\u201d 2022 \u00e8 promosso con la main partnership di <strong>Cobat<\/strong>, la grande piattaforma italiana dell\u2019economia circolare, e con la digital partnership di <strong>Bluarancio<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Il contest<\/strong>. \u00c8 aperto a tutti i cittadini, italiani e stranieri, residenti o domiciliati in Italia che abbiano compiuto i 18 anni di et\u00e0 entro il 3 marzo 2022. <strong>Dal 5 giugno 2021 (Giornata mondiale dell\u2019ambiente) al 3 marzo 2022 (Giornata mondiale della fauna selvatica), i partecipanti al concorso possono inviare un\u2019immagine scattata in un Parco Nazionale, Regionale, Interregionale, in un&#8217;Area Marina Protetta o in una Riserva, Statale o Regionale<\/strong>.<\/p>\n<p>La partecipazione \u00e8 totalmente gratuita, baster\u00e0 registrarsi sul <a href=\"http:\/\/www.obiettivoterra.eu\">portale<\/a> e caricare una fotografia a colori, secondo le caratteristiche tecniche previste dal regolamento del concorso. \u00c8 ammessa la candidatura di una sola foto per partecipante.<\/p>\n<p><strong>Premio Mother Earth Day<\/strong>. Al vincitore di \u201cObiettivo Terra\u201d 2022, oltre al primo premio di \u20ac 1.000 (euro mille) e all&#8217;onore di veder esposta al pubblico la gigantografia della propria foto in una delle piazze centrali di Roma, sar\u00e0 donata una targa ricordo dai soggetti promotori e dedicata la copertina del volume \u201cObiettivo Terra 2022: l\u2019Italia amata dagli italiani\u201d.<\/p>\n<p><em><strong>Alfonso Pecoraro Scanio (Presidente Fondazione UniVerde): <\/strong><\/em><em>\u201cLa ripartenza passa dalla tutela dell&#8217;ambiente, dalla valorizzazione dei nostri Parchi naturali e dalla promozione di un turismo sempre pi\u00f9 sostenibile, diffuso e smart. \u00c8 fondamentale che l\u2019impegno per l\u2019emergenza climatica sia concreto e costante, perch\u00e9 solo cos\u00ec si potr\u00e0 giungere al vero cambiamento culturale di cui la nostra epoca ha bisogno come risposta alle nuove sfide di questo millennio e la pandemia ce lo insegna\u201d.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em><strong>Claudio Cerreti (Presidente Societ\u00e0 Geografica Italiana): <\/strong><\/em><em>\u201cLa salvaguardia e la valorizzazione del patrimonio naturalistico \u00e8 uno scopo, ma soprattutto un mezzo. Uno scopo, ovviamente, perch\u00e9 non possiamo pi\u00f9 permetterci di consumare l\u2019ambiente sapendo fin troppo bene che non lo sappiamo rigenerare; e un mezzo, nel senso che incorporare sempre pi\u00f9, nei comportamenti quotidiani, la cura convinta del nostro ambiente di vita sollecita l\u2019attenzione a una vera sostenibilit\u00e0 del nostro modo di vivere, produrre, consumare; sollecita una presa di coscienza che va al di l\u00e0 della sola tutela, verso la richiesta di opzioni politiche che modifichino alla radice la postura verso il non-umano; sollecita, infine, la consapevolezza di quanto sia ricca, diversa e insostituibile la realt\u00e0, oltre il modesto orizzonte di ciascuno di noi come individuo, e apre alla comprensione e al rispetto verso l\u2019Altro, umano e non-umano\u201d.<\/em><\/p>\n<p><em><strong>\u00a0<\/strong><\/em><\/p>\n<p><em><strong>Giancarlo Morandi (Presidente Cobat): <\/strong><\/em><em>\u201cLa quasi totalit\u00e0 dell\u2019umanit\u00e0\u00a0 si \u00e8 finalmente resa conto, nonostante la pandemia in atto ancora da debellare, della necessit\u00e0 di mantenere abitabile la terra per gli esseri umani. Cobat anticipando i tempi ha compreso che non bastava pi\u00f9 semplicemente ottimizzare i propri processi logistici ed industriali ma che bisognava affrontare i problemi con una filosofia pi\u00f9 attenta all\u2019uomo e alla sua cultura per risvegliarne la capacit\u00e0 di diventare attore consapevole di un nuovo sviluppo\u201d.<\/em><\/p>\n<p><em><strong>\u00a0<\/strong><\/em><\/p>\n<p><strong>Menzioni e Menzioni Speciali<\/strong>.<\/p>\n<p>Oltre al primo premio saranno selezionate, tra le foto ammesse, le vincitrici delle Menzioni per ognuna delle seguenti categorie:\u00a0Alberi e foreste (in collaborazione con Comando Unit\u00e0 forestali, ambientali e agroalimentari dei Carabinieri); Animali (in collaborazione con Federparchi); Area costiera (in collaborazione con Corpo delle Capitanerie di porto \u2013 Guardia Costiera); Fiumi e laghi (in collaborazione con Federazione Italiana Canoa e Kayak);\u00a0Paesaggio agricolo (in collaborazione con Fondazione Campagna Amica); Patrimonio geologico e geodiversit\u00e0 (in collaborazione con Societ\u00e0 Italiana di Geologia Ambientale); Turismo sostenibile (in collaborazione con Touring Club Italiano).<\/p>\n<p>Per l&#8217;edizione 2022 sono confermate le Menzioni speciali: <strong>Borghi <\/strong>(alla pi\u00f9 bella foto di un borgo all\u2019interno di un&#8217;Area Protetta italiana, in collaborazione con l\u2019Associazione \u201c<strong>I borghi pi\u00f9 belli d\u2019Italia<\/strong>\u201d); <strong>Obiettivo Mare<\/strong> (alla migliore foto subacquea scattata in un&#8217;Area Marina Protetta, in collaborazione con <strong>Marevivo<\/strong>); <strong>Obiettivo Roma<\/strong> (alla pi\u00f9 bella foto scattata nelle Aree Protette della <strong>Citt\u00e0 Metropolitana di Roma Capitale<\/strong>); <strong>Parchi dal cielo<\/strong> (alla pi\u00f9 bella foto scattata con un drone nelle Aree Protette, in collaborazione con <strong>Cobat<\/strong>. Premio conferito solo a chi \u00e8 in possesso delle necessarie autorizzazioni e per fini di monitoraggio, tutela e conservazione della biodiversit\u00e0).<\/p>\n<p>\u00c8 infine previsto il <strong>Premio \u201cParco Inclusivo\u201d 2022<\/strong>, in collaborazione con <strong>FIABA Onlus<\/strong> e <strong>Federparchi<\/strong>, all\u2019Area Protetta che si sia maggiormente distinta, attraverso iniziative concrete, per favorire l&#8217;accessibilit\u00e0 e la fruibilit\u00e0 per le persone con disabilit\u00e0 e a ridotta mobilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Info sul contest anche sulla <strong>nuova versione del sito della <a href=\"http:\/\/www.fondazioneuniverde.it\">Fondazione UniVerde<\/a><\/strong>\u00a0 che celebra la Giornata Mondiale dell&#8217;Ambiente con il restyling del portale web: nuova veste grafica e nuova sezione notizie aggiornata e implementata, per offrire una navigazione pi\u00f9 fluida e intuitiva e consentendo di accedere pi\u00f9 facilmente alle informazioni disponibili su news, campagne, petizioni, attivit\u00e0 e eventi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al via dal 5 giugno \u201cObiettivo Terra\u201d 2022, la nuova edizione del concorso di fotografia geografico-ambientale promosso da Fondazione UniVerde e Societ\u00e0 Geografica Italiana Onlus, dedicato alla difesa e alla valorizzazione del patrimonio ambientale, del paesaggio, dei borghi, delle peculiarit\u00e0 e delle tradizioni enogastronomiche, agricole, artigianali, storico-culturali e sociali dei Parchi Nazionali, Regionali, Interregionali, delle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5973,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[127],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d&#039;Italia -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d&#039;Italia -\" \/>\n<meta property=\"og:description\" content=\"Al via dal 5 giugno \u201cObiettivo Terra\u201d 2022, la nuova edizione del concorso di fotografia geografico-ambientale promosso da Fondazione UniVerde e Societ\u00e0 Geografica Italiana Onlus, dedicato alla difesa e alla valorizzazione del patrimonio ambientale, del paesaggio, dei borghi, delle peculiarit\u00e0 e delle tradizioni enogastronomiche, agricole, artigianali, storico-culturali e sociali dei Parchi Nazionali, Regionali, Interregionali, delle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-07T09:02:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-07-alle-11.01.51.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1244\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/\",\"name\":\"Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d'Italia -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-07-alle-11.01.51.png\",\"datePublished\":\"2021-06-07T09:02:51+00:00\",\"dateModified\":\"2021-06-07T09:02:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-07-alle-11.01.51.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-07-alle-11.01.51.png\",\"width\":1244,\"height\":806},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d&#8217;Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d'Italia -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/","og_locale":"it_IT","og_type":"article","og_title":"Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d'Italia -","og_description":"Al via dal 5 giugno \u201cObiettivo Terra\u201d 2022, la nuova edizione del concorso di fotografia geografico-ambientale promosso da Fondazione UniVerde e Societ\u00e0 Geografica Italiana Onlus, dedicato alla difesa e alla valorizzazione del patrimonio ambientale, del paesaggio, dei borghi, delle peculiarit\u00e0 e delle tradizioni enogastronomiche, agricole, artigianali, storico-culturali e sociali dei Parchi Nazionali, Regionali, Interregionali, delle [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-06-07T09:02:51+00:00","og_image":[{"width":1244,"height":806,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-07-alle-11.01.51.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/","name":"Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d'Italia -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-07-alle-11.01.51.png","datePublished":"2021-06-07T09:02:51+00:00","dateModified":"2021-06-07T09:02:51+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-07-alle-11.01.51.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-07-alle-11.01.51.png","width":1244,"height":806},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/obiettivo-terra-2022-al-via-la-13a-edizione-del-concorso-nazionale-aree-protette-ditalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Obiettivo terra 2022. Al via la 13a edizione del concorso nazionale Aree Protette d&#8217;Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5972"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5972"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5972\/revisions"}],"predecessor-version":[{"id":5974,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5972\/revisions\/5974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5973"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}