{"id":5980,"date":"2021-06-09T16:40:27","date_gmt":"2021-06-09T14:40:27","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=5980"},"modified":"2021-06-09T16:46:13","modified_gmt":"2021-06-09T14:46:13","slug":"quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/","title":{"rendered":"Quale cyber security con il Piano Nazionale di Ripresa e Resilienza?"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\">G<\/span>rande attenzione per la digitalizzazione del paese con investimenti per circa 35 miliardi e l\u2019obiettivo dichiarato di imprimere una decisa accelerazione in tema di innovazione sia a livello industriale, sia a livello della Pubblica Amministrazione.<\/p>\n<p>Il Piano Nazionale di Ripresa e Resilienza (PNRR) ha suscitato grandi aspettative tra i professionisti che operano nel settore digitale e, almeno sulla carta, rappresenta un\u2019occasione unica per ammodernare il paese dotandolo di quegli strumenti digitali che possono portare un elevato livello di efficienza e creare margini di sviluppo in tutti i settori.<\/p>\n<p>Tra i vari aspetti affrontati nel capitolo digitalizzazione, per\u00f2, quello della cyber security sconta un\u2019indeterminatezza che, per molti esperti del settore, porta con s\u00e9 il concreto rischio di lasciare \u201cscoperte\u201d le nuove infrastrutture.<\/p>\n<p>L\u2019equivoco della cyber security nel PNRR<br \/>\nIl capitolo dedicato specificatamente alla cyber security all\u2019interno del documento redatto dal governo riguarda un settore limitato della security. Oltre a un budget piuttosto sottodimensionato (solo 623 milioni di euro) il punto si concentra sugli aspetti di sicurezza informatica legati a quelli che si possono definire \u201cgli interessi nazionali\u201d, cio\u00e8 le infrastrutture critiche, le forze di polizia e i nuovi enti (forse ne sono previsti anche troppi) cui verranno affidati compiti come l\u2019assessment di software e hardware.<br \/>\nPer quanto riguarda il settore pubblico, gli unici riferimenti specifici alla cyber security si trovano nel capitolo dedicato alla Pubblica Amministrazione, mentre per il settore della cultura, si parla soltanto di interventi \u201cfacendo leva sulle nuove tecnologie per offrire nuovi servizi e migliorare l\u2019accesso alle risorse turistiche\/culturali\u201d. Insomma: per quanto riguarda le strutture legate al settore culturale, la sicurezza non viene indicata come prioritaria.<\/p>\n<p>Una situazione emergenziale<br \/>\nLa preoccupazione per il ruolo che occuper\u00e0 la cyber security in questo processo di evoluzione a livello degli enti culturali affonda e sue radici in uno status quo che ha tratti sconsolanti.<br \/>\nBuona parte delle organizzazioni che operano sul territorio del nostro paese ha a disposizione strumenti digitali obsoleti, la cui gestione non poggia su policy definite e non \u00e8 sottoposta ad alcuna verifica.<br \/>\nIl risultato \u00e8 un quadro che lascia esposti gli enti culturali al rischio di subire attacchi informatici che mettono a repentaglio non solo la disponibilit\u00e0 dei servizi, ma anche l\u2019integrit\u00e0 dei dati trattati, con evidenti ripercussioni sulla privacy dei cittadini che sfruttano i servizi erogati. Da un punto di vista logico (e strategico), di conseguenza, colmare questo gap dovrebbe essere considerato prioritario.<\/p>\n<p>I segnali incoraggianti sono tra le righe?<br \/>\nLe speranze legate all\u2019avvio di un processo di irrobustimento a livello di sicurezza anche nel settore pubblico dedicato ai beni culturali risiedono nella considerazione che il PNRR, allo stato, \u00e8 pur sempre un piano articolato in titoli, i cui dettagli verranno definiti in corso di applicazione.<\/p>\n<p>Alcuni spunti, in ogni caso, sono rintracciabili anche in questa fase e in particolare, laddove si trovano alcuni riferimenti a obiettivi di pi\u00f9 ampio respiro, come quando si indica la volont\u00e0 di mettere in atto nella Pubblica Amministrazione \u201cinterventi di supporto per l\u2019acquisizione e l\u2019arricchimento delle competenze digitali\u201d. Se questo (indispensabile) processo di formazione comprender\u00e0 la cyber security, possiamo sperare in qualcosa di buono.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"p1\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande attenzione per la digitalizzazione del paese con investimenti per circa 35 miliardi e l\u2019obiettivo dichiarato di imprimere una decisa accelerazione in tema di innovazione sia a livello industriale, sia a livello della Pubblica Amministrazione. Il Piano Nazionale di Ripresa e Resilienza (PNRR) ha suscitato grandi aspettative tra i professionisti che operano nel settore digitale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5983,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[632],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quale cyber security con il Piano Nazionale di Ripresa e Resilienza? -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quale cyber security con il Piano Nazionale di Ripresa e Resilienza? -\" \/>\n<meta property=\"og:description\" content=\"Grande attenzione per la digitalizzazione del paese con investimenti per circa 35 miliardi e l\u2019obiettivo dichiarato di imprimere una decisa accelerazione in tema di innovazione sia a livello industriale, sia a livello della Pubblica Amministrazione. Il Piano Nazionale di Ripresa e Resilienza (PNRR) ha suscitato grandi aspettative tra i professionisti che operano nel settore digitale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T14:40:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-09T14:46:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-09-alle-16.45.22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1190\" \/>\n\t<meta property=\"og:image:height\" content=\"932\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/\",\"name\":\"Quale cyber security con il Piano Nazionale di Ripresa e Resilienza? -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-09-alle-16.45.22.png\",\"datePublished\":\"2021-06-09T14:40:27+00:00\",\"dateModified\":\"2021-06-09T14:46:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-09-alle-16.45.22.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-09-alle-16.45.22.png\",\"width\":1190,\"height\":932},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quale cyber security con il Piano Nazionale di Ripresa e Resilienza?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quale cyber security con il Piano Nazionale di Ripresa e Resilienza? -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/","og_locale":"it_IT","og_type":"article","og_title":"Quale cyber security con il Piano Nazionale di Ripresa e Resilienza? -","og_description":"Grande attenzione per la digitalizzazione del paese con investimenti per circa 35 miliardi e l\u2019obiettivo dichiarato di imprimere una decisa accelerazione in tema di innovazione sia a livello industriale, sia a livello della Pubblica Amministrazione. Il Piano Nazionale di Ripresa e Resilienza (PNRR) ha suscitato grandi aspettative tra i professionisti che operano nel settore digitale [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-06-09T14:40:27+00:00","article_modified_time":"2021-06-09T14:46:13+00:00","og_image":[{"width":1190,"height":932,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-09-alle-16.45.22.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/","name":"Quale cyber security con il Piano Nazionale di Ripresa e Resilienza? -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-09-alle-16.45.22.png","datePublished":"2021-06-09T14:40:27+00:00","dateModified":"2021-06-09T14:46:13+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-09-alle-16.45.22.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/06\/Schermata-2021-06-09-alle-16.45.22.png","width":1190,"height":932},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/quale-cyber-security-con-il-piano-nazionale-di-ripresa-e-resilienza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Quale cyber security con il Piano Nazionale di Ripresa e Resilienza?"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5980"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=5980"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5980\/revisions"}],"predecessor-version":[{"id":5982,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/5980\/revisions\/5982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5983"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=5980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=5980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=5980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}