{"id":609,"date":"2019-04-30T17:51:25","date_gmt":"2019-04-30T15:51:25","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=609"},"modified":"2019-04-30T17:51:25","modified_gmt":"2019-04-30T15:51:25","slug":"la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/","title":{"rendered":"La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span class=\"dropcap dropcap3\">L<\/span>a Banca centrale europea (BCE) stima che nel 2019 le spese per la vigilanza prudenziale delle banche si attestino a 559 milioni di euro.<\/p>\n<p>Tuttavia, l\u2019importo complessivo dei contributi raggiungera\u0300 576 milioni di euro per tenere conto del risultato negativo riportato dal 2018, pari a 15,3 milioni di euro, e delle rettifiche dei contributi individuali, per 1,7 milioni di euro, derivanti da variazioni degli assetti bancari.<\/p>\n<p>La banche vigilate direttamente dalla BCE pagheranno il 91% dei contributi, mentre il restante 9% sara\u0300 a carico delle banche sottoposte alla sua vigilanza indiretta.<\/p>\n<p>L\u2019incremento dei costi stimati (da 502,5 milioni di euro nel 2018 a 559,0 milioni nel 2019) riflette soprattutto l\u2019aumento dell\u2019organico dovuto al trasferimento o all\u2019espansione delle banche, a seguito del recesso del Regno Unito dall\u2019UE (Brexit) e delle corrispondenti valutazioni preliminari.<\/p>\n<p>Inoltre, la BCE svolge attualmente la valutazione approfondita di sei banche bulgare al fine di condurre i negoziati su una cooperazione stretta con la Bulgaria. In aggiunta, il riassetto delle banche di credito cooperativo italiane determinera\u0300 ulteriori costi.<\/p>\n<p>L\u2019ammontare complessivo dei contributi previsto per il 2019 (576 milioni di euro) supera in misura significativa quello relativo al 2018 (474,8 milioni di euro), per via della fatturazione ex ante basata sulla stima dei costi.<\/p>\n<p>In passato la Vigilanza bancaria della BCE ha riportato un risultato positivo dagli anni precedenti (che ha ridotto il contributo totale), mentre a fine 2018 ha rilevato un risultato negativo di 15,3 milioni di euro che confluisce nella stima del contributo per il 2019.<\/p>\n<p>Maggiori informazioni sui contributi annuali complessivi sono disponibili nel sito Internet della BCE dedicato alla vigilanza bancaria.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Le banche riceveranno i rispettivi avvisi di contribuzione a ottobre 2019. Allo stadio attuale e\u0300 in corso una consultazione pubblica sul regime di contribuzione, ivi compresa la proposta di introdurre la fatturazione ex post, anziche\u0301 ex ante.<\/p>\n<p>&nbsp;<\/p>\n<p>Nota<\/p>\n<p>\u25cf Il contributo di vigilanza per singola banca e\u0300 determinato in base alla sua rilevanza e al suo profilo di rischio, utilizzando i fattori annuali per il calcolo della contribuzione forniti da tutti gli enti creditizi vigilati con riferimento al 31 dicembre dell\u2019anno precedente. Il contributo, fissato al massimo livello di consolidamento nell\u2019ambito degli Stati membri partecipanti al Meccanismo di vigilanza unico, e\u0300 ottenuto dalla somma della componente costituita dal contributo minimo a carico di tutte le banche, che rappresenta il 10% dell\u2019importo da recuperare, e della componente variabile del contributo ai fini della ripartizione della quota residua pari al 90% dei costi. Per gli enti significativi piu\u0300 piccoli, con attivi totali pari o inferiori a 10 miliardi di euro, il contributo minimo e\u0300 dimezzato.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Banca centrale europea (BCE) stima che nel 2019 le spese per la vigilanza prudenziale delle banche si attestino a 559 milioni di euro. Tuttavia, l\u2019importo complessivo dei contributi raggiungera\u0300 576 milioni di euro per tenere conto del risultato negativo riportato dal 2018, pari a 15,3 milioni di euro, e delle rettifiche dei contributi individuali, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":610,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[276,163,277],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019 -\" \/>\n<meta property=\"og:description\" content=\"La Banca centrale europea (BCE) stima che nel 2019 le spese per la vigilanza prudenziale delle banche si attestino a 559 milioni di euro. Tuttavia, l\u2019importo complessivo dei contributi raggiungera\u0300 576 milioni di euro per tenere conto del risultato negativo riportato dal 2018, pari a 15,3 milioni di euro, e delle rettifiche dei contributi individuali, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-30T15:51:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Bce.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"959\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/\",\"name\":\"La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Bce.jpg\",\"datePublished\":\"2019-04-30T15:51:25+00:00\",\"dateModified\":\"2019-04-30T15:51:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Bce.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Bce.jpg\",\"width\":959,\"height\":639},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/","og_locale":"it_IT","og_type":"article","og_title":"La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019 -","og_description":"La Banca centrale europea (BCE) stima che nel 2019 le spese per la vigilanza prudenziale delle banche si attestino a 559 milioni di euro. Tuttavia, l\u2019importo complessivo dei contributi raggiungera\u0300 576 milioni di euro per tenere conto del risultato negativo riportato dal 2018, pari a 15,3 milioni di euro, e delle rettifiche dei contributi individuali, [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-04-30T15:51:25+00:00","og_image":[{"width":959,"height":639,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Bce.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/","name":"La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019 -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Bce.jpg","datePublished":"2019-04-30T15:51:25+00:00","dateModified":"2019-04-30T15:51:25+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Bce.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/04\/Bce.jpg","width":959,"height":639},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/la-bce-fissa-a-576-milioni-di-euro-i-contributi-per-le-attivita-di-vigilanza-per-lanno-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"La BCE fissa a 576 milioni di euro i contributi per le attivita\u0300 di vigilanza per l\u2019anno 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/609"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=609"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/609\/revisions"}],"predecessor-version":[{"id":611,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/609\/revisions\/611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/610"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}