{"id":6256,"date":"2021-10-06T10:19:43","date_gmt":"2021-10-06T08:19:43","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=6256"},"modified":"2021-10-06T10:20:24","modified_gmt":"2021-10-06T08:20:24","slug":"concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/","title":{"rendered":"Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa"},"content":{"rendered":"<p>\u00c9 stata presentata lo scorso 29 settembre la relazione Annuale dell\u2019AGCM (Autorit\u00e0 Garante della concorrenza e del mercato) e, come sempre, \u00e8 risultata molto completa nella sua interezza e particolarit\u00e0 delle considerazioni effettuate dall\u2019autorit\u00e0.<\/p>\n<p>Tuttavia, dalla relazione del Presidente Rustichelli, sono emersi dati e azioni che cadono in un momento cruciale della vita dell\u2019Unione Europea &#8211; non solo italiana &#8211; con la gestione dell\u2019emergenza sanitaria in prima fila e l\u2019adozione del Next Generation EU.<\/p>\n<p>\u00c9 interessante soffermarsi su alcuni focus che non debbono sembrare distanti dalla quotidianit\u00e0 dei cittadini ma che, inversamente sono molto addentro il nostro essere utenti e attori della vita economica e sociale nel Paese.<\/p>\n<p>Possiamo iniziare parlando della sleale <i>concorrenza fiscale<\/i> tra gli Stati membri dell\u2019Europa: come afferma il Presidente, esso \u201ccostituisce uno dei pi\u00f9 gravi fattori di distorsione di quel level playing field, che \u00e8 a fondamento di una competizione equa. Il danno arrecato agli Stati che producono valore dal dumping fiscale posto in essere da taluni Paesi europei, divenuti oggi dei veri e propri paradisi fiscali con l\u2019euro, si \u00e8 ancor pi\u00f9 aggravato\u201d.<\/p>\n<p>Infatti, se pensiamo che nel nostro paese, solo nel 2018, sono stati ben 27 i miliardi realizzati dalle multinazionali e spostati nei paradisi fiscali europei; 40 quelli spostati dalla Francia; 71 i profitti sottratti alla tassazione in Germania.<\/p>\n<p>Chi ne beneficia sono sempre sei Stati, Belgio, Cipro Lussemburgo, Irlanda, Olanda e Malta, mentre l\u2019Europa \u00e8 la principale vittima dell\u2019elusione delle grandi societ\u00e0, con oltre il 35% dei profitti spostati dal Vecchio Continente, a fronte di meno del 25% dagli Stati Uniti.<\/p>\n<p>Altro argomento delicato \u00e8 anche il dumping sul piano contributivo e delle tutele del lavoro proveniente da alcuni Paesi dell\u2019Est Europa, che viene aggravata quando i contributi europei vengono utilizzati per conseguire vantaggi, assolutamente indebiti, competitivi e tendono favorire processi di delocalizzazione a scapito di altri Paesi membri.<\/p>\n<p>Ancora una volta \u00e8 chiaro che il persistere di tali fenomeni contrasta radicalmente il principio ispiratore della solidariet\u00e0, fortemente voluto dai Padri fondatori dell\u2019Unione Europea e rischia di compromettere il progetto europeo.<\/p>\n<p>Dal punto di vista etico, nella relazione \u00e8 emerso ad esempio che, sul tema della concorrenza fiscale, il vertice del G20 tenutosi a Venezia lo scorso luglio, si \u00e8 concluso con un accordo di massima che prevede l\u2019introduzione di una global minimum tax pari ad almeno il 15%.<\/p>\n<p>\u00c8 certamente un passo avanti nel contrasto al comportamento delle multinazionali che oggi possono liberamente spostare i profitti nei paradisi fiscali, ma non risolve certo fino in fondo il problema della concorrenza sleale all\u2019interno dell\u2019Unione Europea.<\/p>\n<p>Non lo si risolve n\u00e9 dal punto di vista dell\u2019enforcement, infatti sar\u00e0 complesso applicare in modo uniforme la nuova imposta a causa della mancata standardizzazione dei criteri di calcolo della relativa base imponibile, n\u00e9 appunto dal punto di vista etico, poich\u00e9 continueranno ad esistere Paesi in Europa che, in assenza di regole comuni, continueranno ad abusare della propria autonomia fiscale.<\/p>\n<p><b><i>Pandemia e rispetto del consumatore<\/i><\/b><\/p>\n<p>La pandemia Covid-19, dichiarata tale dall\u2019OMS lo scorso 11 marzo 2020 (purtroppo ancora in atto) ha significato un cambiamento sociale ed economico epocale.<br \/>\nQuesta ha richiesto, da parte dei governi l\u2019adozione di misure efficaci per assicurare l\u2019approvvigionamento di beni e servizi essenziali a prezzi accessibili, per garantire il graduale ripristino di filiere produttive e distributive temporaneamente bloccate.<br \/>\nIl conseguimento di tali obiettivi ha reso necessarie forme pi\u00f9 o meno intense di cooperazione tra le imprese per scongiurare il rischio di una carenza di beni e servizi essenziali e questo \u00e8 stato possibile grazie alle vigenti regole di concorrenza, che gi\u00e0 consentono la conclusione di accordi di cooperazione.<\/p>\n<p>Siamo stati chiamati tutti, ognuno nel proprio ambito professionale, a confrontarci con problematiche inedite, inattese e complesse, ad affrontare questo evento traumatico con freddezza e cercando di essere propositivi, individuando risposte celeri e necessarie per reagire prontamente e senza pregiudicare lo status-quo organizzativo sia nei settori privati che pubblici.<br \/>\nQuesta \u00e8 la <b>\u201c<i>resilienza<\/i>\u201d<\/b>cos\u00ec tanto citata \u2013 anche molto a sproposito \u2013 negli ultimi mesi, ma conosciuta solo da chi per professione o per servizio l\u2019ha studiata, progettata, gestita e conosciuta da vicino.<\/p>\n<p>Ciascuno degli attori facente parte del Sistema Paese \u00e8 stato chiamato a dare un contributo che potesse arginare le tantissime criticit\u00e0 e sofferenze emerse nella societ\u00e0 civile.<br \/>\nAnche in questo contesto l\u2019AGCM non ha fatto mancare il suo prezioso contributo in modo trasversale a servizio di cittadini, consumatori, imprese e istituzioni pubbliche, al fine di garantire rapporti economici e commerciali trasparenti ed equilibrati e assicurare mercati concorrenziali.<\/p>\n<p>L\u2019emergenza ha imposto l\u2019esigenza di far ricorso, anche in modo nuovo, a tutti gli strumenti di intervento a disposizione dell\u2019Autorit\u00e0 al fine di tutelare le nuove fragilit\u00e0 indotte dalla pandemia e reprimere le condotte illecite da questa favorite.<br \/>\nSin dall\u2019inizio di questo biennio nero infatti, i consumatori sono apparsi facilmente esposti, pi\u00f9 sensibili e condizionabili nell\u2019acquistare beni o servizi a fronte delle nuove esigenze generate dall\u2019emergenza.<br \/>\nL\u2019Autorit\u00e0 quindi, nell\u2019esercizio delle proprie competenze in materia di tutela del consumatore, ha dovuto dedicare specifiche attenzioni al comportamento e alla condotta poste in essere dagli operatori nei settori economici che maggiormente sono stati interessati dall\u2019impatto della pandemia, in particolare i settori farmaceutico, agroalimentare, del commercio online, del turismo e dei trasporti, del credito.<br \/>\nE\u2019 fuori dubbio quindi che, orientando le proprie azioni ed interventi, l\u2019Autorit\u00e0 abbia saputo adeguare le politiche di concorrenza e di tutela dei consumatori all\u2019eccezionalit\u00e0 del contesto, in linea con le iniziative intraprese in sede europea.<\/p>\n<p><b><i>Investimenti e digitalizzazione <\/i><\/b><\/p>\n<p>Gli elementi cardine di una politica pubblica di sostegno alla ripresa economica ed al recupero della produttivit\u00e0 del sistema economico italiano, oggi pi\u00f9 che mai, sono le infrastrutture e gli investimenti.<\/p>\n<p>Un esempio lampante sono le reti digitali, che costituiscono l\u2019infrastruttura portante dell\u2019economia e la priorit\u00e0 del Next Generation EU.<\/p>\n<p>Oggi il loro sviluppo \u00e8 spesso ostacolato da un quadro normativo che crea incertezze, e da un\u2019applicazione non uniforme dei principi del Codice delle Comunicazioni Elettroniche da parte delle amministrazioni locali e dei concessionari pubblici. I lunghi contenziosi amministrativi spesso creano evidenti ritardi nel processo di infrastrutturazione in fibra del Paese.<\/p>\n<p>Gli ostacoli agli investimenti, dunque, vanno rimossi definendo innanzi tutto una politica pubblica orientata alla realizzazione di una concorrenza infrastrutturale pi\u00f9 estesa.<\/p>\n<p>L\u2019Autorit\u00e0 nel corso del 2020 ha avviato diversi procedimenti aventi ad oggetto i mercati riconducibili alle piattaforme digitali controllate dalle Big Tech (Google, Apple, Facebook, Amazon). In particolare, sulla base di una segnalazione di Enel X Italia, l\u2019Autorit\u00e0 ha approfondito l\u2019analisi dell\u2019ipotesi istruttoria contenuta nel provvedimento di avvio relativa all\u2019esistenza di un rifiuto costruttivo a dare accesso alla sua piattaforma Android Auto alla app di ricerca e navigazione JuicePass (gi\u00e0 Enel X Recharge), sviluppata da Enel per i servizi di localizzazione e prenotazione delle colonnine per la ricarica delle auto elettriche, che costituiva un servizio innovativo in una fase cruciale di sviluppo della mobilit\u00e0 elettrica. Infatti, Google pur definendo correntemente gli strumenti informatici che consentono agli sviluppatori di creare app compatibili con Android Auto, a fronte della richiesta di Enel X Italia, non ha approntato le soluzioni informatiche adeguate, procrastinando, ingiustificatamente, la disponibilit\u00e0 della app di Enel X Italia su Android Auto.<\/p>\n<p>Lo scopo della condotta di Google sarebbe stato quello di escludere un concorrente, che ha sviluppato una app \u201cspecialistica\u201d, cos\u00ec da proteggere e consolidare il modello di business di Google Maps e il suo ruolo di punto di accesso agli utenti e al flusso di dati generato dalle attivit\u00e0 degli stessi.<\/p>\n<p>Sempre nel contesto di sfruttamento dei Big Data come risorsa competitiva strategica, sulla base di una segnalazione di Interactive Advertising Bureau Italia (di seguito anche \u201cIAB\u201d) l\u2019Autorit\u00e0 ha attenzionato Google Alphabet Inc., Google LLC e Google Italy S.r.l..<\/p>\n<p>In questo caso Google, costantemente presente nella pubblicit\u00e0 online e nell\u2019offerta di servizi da questa individuati, ha posto in essere condotte commerciali suscettibili di ostacolare i propri concorrenti non integrati e di mantenere e rafforzare il proprio potere di mercato.<\/p>\n<p>Durante il 2020, inoltre, le restrizioni al commercio e alla circolazione delle hanno portato in primo piano il ruolo cruciale dell\u2019e-commerce e hanno reso pi\u00f9 evidenti gli ostacoli posti dagli operatori gatekeeper quali Amazon e Apple alla rivendita online di prodotti da parte di rivenditori terzi.<\/p>\n<p>Infine, sempre nell\u2019ambito dei servizi di intermediazione sui marketplace, l\u2019Autorit\u00e0 sta proseguendo nell\u2019istruttoria tuttora in corso nei confronti di alcune societ\u00e0 del gruppo Amazon volta a verificare la liceit\u00e0 di alcune condotte che conferirebbero unicamente ai venditori terzi che aderiscono al servizio di logistica offerto da Amazon stessa (\u201cLogistica di Amazon\u201d o \u201cFulfillment by Amazon\u201d) vantaggi in termini di visibilit\u00e0 della propria offerta e di miglioramento delle proprie vendite.<\/p>\n<p>Un assetto istituzionale realmente orientato alla promozione degli investimenti e alla crescita esige regole chiare e certe, un\u2019azione amministrativa qualificata ed efficiente e la riduzione del ricorso alla cosiddetta \u201cburocrazia difensiva\u201d.<\/p>\n<p>Ed \u00e8 qui il cuore di tutto: la burocrazia deve essere a servizio dell\u2019evoluzione, non certo rappresentare sempre un atavico gradino di inciampo.<\/p>\n<p>Questo significa, per il nostro Paese in particolare, avere il coraggio di compiere un salto culturale. Nonostante le complicate condizioni al contorno, la relazione dell\u2019Autorit\u00e0, ci dice che oggi abbiamo gli strumenti per concretizzare una \u201cburocrazia costruttiva\u201d sana ed efficiente, aggiungerei, a tutela della collettivit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 stata presentata lo scorso 29 settembre la relazione Annuale dell\u2019AGCM (Autorit\u00e0 Garante della concorrenza e del mercato) e, come sempre, \u00e8 risultata molto completa nella sua interezza e particolarit\u00e0 delle considerazioni effettuate dall\u2019autorit\u00e0. Tuttavia, dalla relazione del Presidente Rustichelli, sono emersi dati e azioni che cadono in un momento cruciale della vita dell\u2019Unione Europea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6257,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa -\" \/>\n<meta property=\"og:description\" content=\"\u00c9 stata presentata lo scorso 29 settembre la relazione Annuale dell\u2019AGCM (Autorit\u00e0 Garante della concorrenza e del mercato) e, come sempre, \u00e8 risultata molto completa nella sua interezza e particolarit\u00e0 delle considerazioni effettuate dall\u2019autorit\u00e0. Tuttavia, dalla relazione del Presidente Rustichelli, sono emersi dati e azioni che cadono in un momento cruciale della vita dell\u2019Unione Europea [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-06T08:19:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-06T08:20:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/10\/Biagino-Costanzo-e1633508371861.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"622\" \/>\n\t<meta property=\"og:image:height\" content=\"503\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/\",\"name\":\"Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/10\/Biagino-Costanzo-e1633508371861.jpeg\",\"datePublished\":\"2021-10-06T08:19:43+00:00\",\"dateModified\":\"2021-10-06T08:20:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/10\/Biagino-Costanzo-e1633508371861.jpeg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/10\/Biagino-Costanzo-e1633508371861.jpeg\",\"width\":622,\"height\":503},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/","og_locale":"it_IT","og_type":"article","og_title":"Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa -","og_description":"\u00c9 stata presentata lo scorso 29 settembre la relazione Annuale dell\u2019AGCM (Autorit\u00e0 Garante della concorrenza e del mercato) e, come sempre, \u00e8 risultata molto completa nella sua interezza e particolarit\u00e0 delle considerazioni effettuate dall\u2019autorit\u00e0. Tuttavia, dalla relazione del Presidente Rustichelli, sono emersi dati e azioni che cadono in un momento cruciale della vita dell\u2019Unione Europea [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-10-06T08:19:43+00:00","article_modified_time":"2021-10-06T08:20:24+00:00","og_image":[{"width":622,"height":503,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/10\/Biagino-Costanzo-e1633508371861.jpeg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/","name":"Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/10\/Biagino-Costanzo-e1633508371861.jpeg","datePublished":"2021-10-06T08:19:43+00:00","dateModified":"2021-10-06T08:20:24+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/10\/Biagino-Costanzo-e1633508371861.jpeg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/10\/Biagino-Costanzo-e1633508371861.jpeg","width":622,"height":503},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/concorrenza-leale-ai-tempi-del-pnrr-ecco-la-nuova-sfida-per-leuropa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Concorrenza Leale ai tempi del PNRR: ecco la nuova sfida per l\u2019Europa"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6256"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=6256"}],"version-history":[{"count":2,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6256\/revisions"}],"predecessor-version":[{"id":6259,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6256\/revisions\/6259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/6257"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=6256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=6256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=6256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}