{"id":638,"date":"2019-05-06T10:30:49","date_gmt":"2019-05-06T08:30:49","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=638"},"modified":"2019-05-06T10:30:49","modified_gmt":"2019-05-06T08:30:49","slug":"tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/","title":{"rendered":"TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo"},"content":{"rendered":"<p><span class=\"dropcap dropcap3\"><strong>\u00a0<\/strong>S<\/span>ale ad oltre 100 miliardi il valore del falso Made in Italy agroalimentare nel mondo con un aumento record del 70% nel corso dell\u2019ultimo decennio, per effetto della pirateria internazionale che utilizza impropriamente parole, colori, localit\u00e0, immagini, denominazioni e ricette che richiamano all\u2019Italia per alimenti taroccati che non hanno nulla a che fare con il sistema produttivo nazionale.<\/p>\n<p>E\u2019 quanto emerge dall\u2019analisi<strong> Coldiretti e Filiera Italia<\/strong> in occasione dell\u2019apertura di <strong>TUTTOFOOD<\/strong> la <strong>World Food Exibition<\/strong> che si svolge alla Fiera di Milano fino al 9 maggio con le due organizzazioni presenti in uno spazio innovativo nel Padiglione 1 \u2013 Stand A02 \u2013 B01 dove sono smascherati gli ultimi casi piu\u2019 eclatanti di falso Made in Italy a tavola, con l\u2019anteprima della mostra su \u201cL\u2019inganno del falso Made in Italy nel piatto\u201d.<\/p>\n<p>Un fenomeno che rischia di moltiplicarsi con le nuove guerre commerciali a partire dai dazi Usa nei confronti dell\u2019Unione Europea con l\u2019avvio, proprio in occasione dell\u2019apertura di TUTTOFOOD, dell\u2019indagine da parte del Dipartimento del Commercio Usa (USTR) che prevede l\u2019audizione pubblica delle parti interessate e il successivo invio di considerazioni scritte sulle misure proposte dall\u2019Amministrazione Trump entro la fine del mese.<\/p>\n<p>A far esplodere il falso, che ruba all&#8217; Italia trecentomila posti di lavoro, \u00e8 stata paradossalmente la \u201cfame\u201d di Made In Italy\u00a0 all\u2019estero con la proliferazione di imitazioni low cost ma anche le guerre commerciali scaturite dalle tensioni politiche, come dimostra l\u2019embargo russo, con un vero boom nella produzione locale del cibo Made in Italy taroccato, dal salame Italia alla mozzarella \u201cCasa Italia\u201d, dall\u2019insalata \u201cBuona Italia\u201d alla Robiola, ma anche la mortadella Milano, Parmesan o burrata tutti rigorosamente realizzati nel Paese di Putin.<\/p>\n<p>&nbsp;<\/p>\n<p>A preoccupare \u00e8 ora \u2013 continuano Coldiretti e Filiera Italia &#8211;\u00a0 l\u2019emergere di misure protezionistiche e la chiusura delle frontiere a partire dalla minaccia di Trump che mettere i dazi sui prodotti europei con la pubblicazione di un black list dei prodotti europei da colpire per un importo complessivo di 11 miliardi di dollari che comprende anche importanti prodotti agroalimentari di interesse nazionale come i vini tra i quali il Prosecco ed il Marsala, formaggi, ma anche l\u2019olio di oliva, gli agrumi, l\u2019uva, le marmellate, i succhi di frutta, l\u2019acqua e i superalcolici tra gli alimentari e le bevande colpite.<\/p>\n<p>Con i dazi aumenterebbero i prezzi dei prodotti italiani sul mercato americano e sarebbero pi\u00f9 competitive le falsificazioni ottenute sul territorio statunitense e quelle provenienti da Paesi non colpiti dalle misure di Trump. Basta pensare che il 90% dei formaggi di tipo italiano in Usa \u2013 sottolinea la Coldiretti \u2013 sono in realt\u00e0 realizzati in Wisconsin, California e New York, dal Parmesan al Romano senza latte di pecora, dall\u2019Asiago al Gorgonzola fino al Fontiago, un improbabile mix tra Asiago e Fontina.<\/p>\n<p>Ma il problema riguarda tutte le categorie merceologiche come l\u2019olio Pompeian made in Usa, i salumi pi\u00f9 prestigiosi, dalle imitazioni del Parma e del San Daniele alla mortadella Bologna o al salame Milano, senza dimenticare i pomodori, come il San Marzano che viene prodotto in California e venduto in tutti gli Stati Uniti.<\/p>\n<p>Un pericolo che \u2013 precisano Coldiretti e Filiera Italia &#8211; riguarda anche la Brexit poich\u00e9 nel caso di uscita della Gran Bretagna senza accordo con l\u2019Unione Europea non sarebbe garantita la stessa tutela giuridica dei prodotti a denominazione di origine che, senza protezione europea, rischiano di subire la concorrenza sleale dei prodotti di imitazione.<\/p>\n<p>Basta pensare ai casi, smascherati in passato in Gran Bretagna, della vendita di falso prosecco alla spina o in lattina fino ai wine kit o ai parmesan kit.<\/p>\n<p>Nonostante il record fatto segnare nelle esportazioni agroalimentari Made in Italy che nel 2018 hanno raggiunto il valore di 41,8 miliardi, oggi piu\u2019 di due prodotti di tipo italiano su tre venduti nel mondo sono falsi con il fenomeno del cosiddetto italian sounding che colpisce in misura diversa tutti i prodotti, dai salumi alle conserve, dal vino ai formaggi ma anche extravergine, sughi o pasta e riguarda tutti i continenti.<\/p>\n<p>In realt\u00e0 a differenza di quanto avviene per altri articoli come la moda o la tecnologia, a taroccare il cibo italiano non sono i Paesi poveri, ma soprattutto quelli emergenti o i pi\u00f9 ricchi a partire proprio dagli Stati Uniti e dall\u2019Australia.<\/p>\n<p>In testa alla classifica dei prodotti pi\u00f9 taroccati secondo la Coldiretti ci sono i formaggi, a partire dal <strong>Parmigiano Reggiano e dal Grana Padano,<\/strong> con la produzione delle copie che ha superato quella degli originali, dal parmesao brasiliano al reggianito argentino fino al parmesan diffuso in tuti i continenti. Ma ci sono anche le imitazioni di <strong>Provolone, Gorgonzola, Pecorino Romano, Asiago o Fontina.<\/strong><\/p>\n<p><strong>Tra i salumi sono clonati i pi\u00f9 prestigiosi, dal Parma al San Daniele<\/strong>, ma anche la <strong>mortadella Bologna<\/strong> o il salame cacciatore e gli extravergine di oliva o le conserve come il <strong>pomodoro San Marzano<\/strong> che viene prodotto in California e venduto in tutti gli Stati Uniti.<\/p>\n<p>Dal <strong>Bordolino argentino<\/strong> nella versione bianco e rosso con tanto di bandiera tricolore al <strong>Kressecco tedesco<\/strong>, oltre al <strong>Barbera bianco<\/strong> prodotto in Romania e al <strong>Chianti<\/strong> fatto in California, il <strong>Marsala sudamericano e quello statunitense<\/strong> sono invece solo alcuni esempi delle contraffazioni e imitazioni dei nostri vini e liquori pi\u00f9 prestigiosi.<\/p>\n<p>&nbsp;<\/p>\n<p>Sulle nuove sfide dell\u2019agroalimentare nazionale domani marted\u00ec 7 maggio 2019 alle ore 14,30 all\u2019Auditorium della Fiera di Milano a Rho parteciper\u00e0 al Forum organizzato da Filiera Italia e Coldiretti a TUTTOFOOD il premier <strong>Giuseppe Conte<\/strong> che in piu\u2019 occasioni ha ricordato l&#8217;importanza della tutela e promozione delle indicazioni geografiche l Made in Italy.<\/p>\n<p>Le imprese agricole italiane e i principali marchi dell\u2019industria alimentare nazionale, riuniti in una storica alleanza, presentano al presidente del Consiglio una realt\u00e0 da primato del Made in Italy nel mondo ma anche le criticit\u00e0 da affrontare ed i progetti di crescita da realizzare in Italia e all\u2019estero.<\/p>\n<p>Sar\u00e0 illustrato il primo studio sul valore della filiera agroalimentare italiana dal presidente del <strong>Censis Giuseppe De Rita.<\/strong><\/p>\n<p>All\u2019incontro partecipano, tra gli altri, il Presidente della Regione Lombardia<strong> Attilio Fontana<\/strong>, l\u2019 Assessore agricoltura e alimentazione della regione Lombardia <strong>Fabio Rolfi<\/strong>, il Presidente Fondazione Fiera Milano<strong> Giovanni Gorno Tempini<\/strong>, il Presidente dell\u2019ICE <strong>Carlo Ferro<\/strong>, il Presidente Confindustria Lombardia <strong>Marco Bonometti, Nunzio Tartaglia<\/strong> responsabile direzione CDP imprese,\u00a0<strong> Paolo De Castro<\/strong> Presidente Comitato Scientifico Filiera Italia oltre al Consigliere delegato Filiera Italia Luigi Scordamaglia e al Presidente di Coldiretti<strong> Ettore Prandini.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Sale ad oltre 100 miliardi il valore del falso Made in Italy agroalimentare nel mondo con un aumento record del 70% nel corso dell\u2019ultimo decennio, per effetto della pirateria internazionale che utilizza impropriamente parole, colori, localit\u00e0, immagini, denominazioni e ricette che richiamano all\u2019Italia per alimenti taroccati che non hanno nulla a che fare con il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":639,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[305,304,303],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo -\" \/>\n<meta property=\"og:description\" content=\"\u00a0Sale ad oltre 100 miliardi il valore del falso Made in Italy agroalimentare nel mondo con un aumento record del 70% nel corso dell\u2019ultimo decennio, per effetto della pirateria internazionale che utilizza impropriamente parole, colori, localit\u00e0, immagini, denominazioni e ricette che richiamano all\u2019Italia per alimenti taroccati che non hanno nulla a che fare con il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T08:30:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/TUTTO-FOOD-FALSI-MADE-IN-ITALY.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/\",\"name\":\"TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/TUTTO-FOOD-FALSI-MADE-IN-ITALY.jpg\",\"datePublished\":\"2019-05-06T08:30:49+00:00\",\"dateModified\":\"2019-05-06T08:30:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/TUTTO-FOOD-FALSI-MADE-IN-ITALY.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/TUTTO-FOOD-FALSI-MADE-IN-ITALY.jpg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/","og_locale":"it_IT","og_type":"article","og_title":"TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo -","og_description":"\u00a0Sale ad oltre 100 miliardi il valore del falso Made in Italy agroalimentare nel mondo con un aumento record del 70% nel corso dell\u2019ultimo decennio, per effetto della pirateria internazionale che utilizza impropriamente parole, colori, localit\u00e0, immagini, denominazioni e ricette che richiamano all\u2019Italia per alimenti taroccati che non hanno nulla a che fare con il [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2019-05-06T08:30:49+00:00","og_image":[{"width":2016,"height":1512,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/TUTTO-FOOD-FALSI-MADE-IN-ITALY.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/","name":"TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/TUTTO-FOOD-FALSI-MADE-IN-ITALY.jpg","datePublished":"2019-05-06T08:30:49+00:00","dateModified":"2019-05-06T08:30:49+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/TUTTO-FOOD-FALSI-MADE-IN-ITALY.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/05\/TUTTO-FOOD-FALSI-MADE-IN-ITALY.jpg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tuttofood-100-mld-di-falso-cibo-made-in-italy-nel-mondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"TuttoFood: 100 MLD di falso cibo Made in Italy nel mondo"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/638"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=638"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/638\/revisions"}],"predecessor-version":[{"id":640,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/638\/revisions\/640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/639"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}