{"id":6429,"date":"2021-12-06T10:28:31","date_gmt":"2021-12-06T09:28:31","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=6429"},"modified":"2021-12-06T10:28:31","modified_gmt":"2021-12-06T09:28:31","slug":"green-pass-uecoop-per-90-imprese-vaccini-salvano-natale","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/","title":{"rendered":"Green pass, Uecoop: per 90% imprese, vaccini salvano Natale"},"content":{"rendered":"<p>Per la schiacciante maggioranza (90%) delle imprese la campagna vaccinale contro il Covid con l\u2019introduzione del super green pass aiuta la ripresa dell\u2019economia e salva il Natale degli italiani. E\u2019 quanto emerge dal monitoraggio dell\u2019Unione europea delle cooperative (Uecoop) su un campione nazionale di realt\u00e0 produttive e di servizi in merito agli effetti delle misure varate dal Governo per prevenire i contagi e preservare la normalit\u00e0 dei cittadini, dallo shopping alle tavolate, in vista delle feste di fine anno.<\/p>\n<p>&nbsp;<\/p>\n<p>Anche se esiste una nicchia di scettici (10%) che non crede all\u2019utilit\u00e0 dei vaccini per la ripresa dell\u2019economia, l\u2019adesione della grande maggioranza della popolazione alla somministrazione dei sieri anti coronavirus anche con la terza dose sta creando \u2013 secondo le rilevazioni di Uecoop \u2013 le condizioni per un clima di speranza per la ripartenza dell\u2019economia, nonostante i timori legati alla diffusione della variante Omicron.<\/p>\n<p>&nbsp;<\/p>\n<p>Una svolta importante che arriva dopo quasi due anni di pesante impatto pandemico sull\u2019economia al quale ha fatto argine la tradizionale resilienza del sistema delle imprese cooperative italiane che \u2013 continua Uecoop &#8211; pu\u00f2 contare su quasi 80mila realt\u00e0 con oltre un milione di occupati e una presenza trasversale su pi\u00f9 settori produttivi e servizi, dalla logistica al turismo, dall\u2019alimentare alla sanit\u00e0, dalla scuola agli spettacoli.<\/p>\n<p>&nbsp;<\/p>\n<p>Le feste di Natale e Capodanno \u2013 conclude Uecoop \u2013 rappresentano un momento strategico per molte imprese cooperative, dalla logistica ai trasporti, dal turismo all\u2019alimentare, dal tempo libero alla fornitura di servizi generali con un trend in crescita che parte da ottobre e prosegue fino alla fine dell\u2019anno creando un giro d\u2019affari da oltre 14 miliardi secondo Coldiretti per le spese delle famiglie, tra viaggi, svaghi e cibo nel periodo delle feste per il quale si muove il sistema produttivo nazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per la schiacciante maggioranza (90%) delle imprese la campagna vaccinale contro il Covid con l\u2019introduzione del super green pass aiuta la ripresa dell\u2019economia e salva il Natale degli italiani. E\u2019 quanto emerge dal monitoraggio dell\u2019Unione europea delle cooperative (Uecoop) su un campione nazionale di realt\u00e0 produttive e di servizi in merito agli effetti delle misure [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2168,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Green pass, Uecoop: per 90% imprese, vaccini salvano Natale -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Green pass, Uecoop: per 90% imprese, vaccini salvano Natale -\" \/>\n<meta property=\"og:description\" content=\"Per la schiacciante maggioranza (90%) delle imprese la campagna vaccinale contro il Covid con l\u2019introduzione del super green pass aiuta la ripresa dell\u2019economia e salva il Natale degli italiani. E\u2019 quanto emerge dal monitoraggio dell\u2019Unione europea delle cooperative (Uecoop) su un campione nazionale di realt\u00e0 produttive e di servizi in merito agli effetti delle misure [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-06T09:28:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/alberi-di-natale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/\",\"name\":\"Green pass, Uecoop: per 90% imprese, vaccini salvano Natale -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/alberi-di-natale.jpg\",\"datePublished\":\"2021-12-06T09:28:31+00:00\",\"dateModified\":\"2021-12-06T09:28:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/alberi-di-natale.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/alberi-di-natale.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Green pass, Uecoop: per 90% imprese, vaccini salvano Natale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Green pass, Uecoop: per 90% imprese, vaccini salvano Natale -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/","og_locale":"it_IT","og_type":"article","og_title":"Green pass, Uecoop: per 90% imprese, vaccini salvano Natale -","og_description":"Per la schiacciante maggioranza (90%) delle imprese la campagna vaccinale contro il Covid con l\u2019introduzione del super green pass aiuta la ripresa dell\u2019economia e salva il Natale degli italiani. E\u2019 quanto emerge dal monitoraggio dell\u2019Unione europea delle cooperative (Uecoop) su un campione nazionale di realt\u00e0 produttive e di servizi in merito agli effetti delle misure [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-12-06T09:28:31+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/alberi-di-natale.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/","name":"Green pass, Uecoop: per 90% imprese, vaccini salvano Natale -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/alberi-di-natale.jpg","datePublished":"2021-12-06T09:28:31+00:00","dateModified":"2021-12-06T09:28:31+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/alberi-di-natale.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/12\/alberi-di-natale.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/green-pass-uecoop-per-90-imprese-vaccini-salvano-natale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Green pass, Uecoop: per 90% imprese, vaccini salvano Natale"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6429"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=6429"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6429\/revisions"}],"predecessor-version":[{"id":6430,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6429\/revisions\/6430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/2168"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=6429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=6429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=6429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}