{"id":6454,"date":"2021-12-20T10:33:51","date_gmt":"2021-12-20T09:33:51","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=6454"},"modified":"2021-12-20T10:33:51","modified_gmt":"2021-12-20T09:33:51","slug":"airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/","title":{"rendered":"Airtime si rafforza e lancia il &#8220;Piano USA 2023&#8221;: obiettivo crescere nei prossimi 24 mesi sul mercato americano"},"content":{"rendered":"<p><span style=\"font-family: garamond, times new roman, serif; font-size: large;\">Rafforzare nei prossimi ventiquattro mesi la presenza su tutto il territorio americano: nasce con questo obiettivo il &#8220;Piano USA 2023&#8221; di Airtime Partecipazioni S.p.A., player attivo nel fintech, che ha completato a settembre il processo di direct listing e dal 22 settembre \u00e8 quotata sul listino Euronext Growth. La societ\u00e0 sviluppa tecnologie innovative nell\u2019ambito delle telecomunicazioni e dei servizi finanziari ed \u00e8 presente nei mercati di Europa e Stati Uniti.<\/span><\/p>\n<p><span style=\"font-family: garamond, times new roman, serif; font-size: large;\"><br \/>\nNell&#8217;ambito del Piano, \u00e8 diventata operativa da dicembre la joint venture con Phonetime e Matchcom, realt\u00e0 attive da oltre 20 anni nel mercato del traffico voce e SMS con oltre 450 clienti in tutto il mondo.<\/p>\n<p>&#8220;Con questo piano &#8211; spiega il ceo di Airtime Orlando Taddeo &#8211; andremo a rafforzare la nostra offerta negli Usa, nelle Americhe e a livello internazionale.<\/span><\/p>\n<p><span style=\"font-family: garamond, times new roman, serif; font-size: large;\"><br \/>\nQuesta partnership permetter\u00e0 alla nostra organizzazione di integrarsi con due realt\u00e0 cos\u00ec importanti e dal respiro internazionale, garantendo loro un ulteriore impulso grazie all\u2019applicazione dei nostri modelli tecnologici e di funding, che permetteranno una considerevole ottimizzazione dei processi operativi e di sviluppo dei modelli di business.<\/span><\/p>\n<p><span style=\"font-family: garamond, times new roman, serif; font-size: large;\"><br \/>\nViviamo in un momento storico in cui i volumi di traffico nelle telecomunicazioni sono cresciuti enormemente. Con la nostra piattaforma Airtime Exchange \u00a0abbiamo creato un ecosistema che aggrega operatori di tutto il mondo. Acquistano e vendono servizi di terminazione voce e sms attraverso tecnologie innovative che permettono transazioni in tempo reale con i pi\u00f9 alti standard di sicurezza. Con lo sviluppo di sistemi finanziari integrati, offriamo modalit\u00e0 di pagamento real time che hanno completamente eliminato il rischio di credito.&#8221;<br \/>\nLe partnership sono state siglate da Airtime Usa, societ\u00e0 controllata al cento per cento da Airtime Partecipazioni S.p.A.<\/span><\/p>\n<p><span style=\"font-family: garamond, times new roman, serif; font-size: large;\"><br \/>\nLa societ\u00e0 \u00e8 stata affiancata nel processo di quotazione da Iniziativa come advisor finanziario e Deloitte Legal come advisor legale.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rafforzare nei prossimi ventiquattro mesi la presenza su tutto il territorio americano: nasce con questo obiettivo il &#8220;Piano USA 2023&#8221; di Airtime Partecipazioni S.p.A., player attivo nel fintech, che ha completato a settembre il processo di direct listing e dal 22 settembre \u00e8 quotata sul listino Euronext Growth. La societ\u00e0 sviluppa tecnologie innovative nell\u2019ambito delle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6455,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[1817,1816,1818],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Airtime si rafforza e lancia il &quot;Piano USA 2023&quot;: obiettivo crescere nei prossimi 24 mesi sul mercato americano -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Airtime si rafforza e lancia il &quot;Piano USA 2023&quot;: obiettivo crescere nei prossimi 24 mesi sul mercato americano -\" \/>\n<meta property=\"og:description\" content=\"Rafforzare nei prossimi ventiquattro mesi la presenza su tutto il territorio americano: nasce con questo obiettivo il &#8220;Piano USA 2023&#8221; di Airtime Partecipazioni S.p.A., player attivo nel fintech, che ha completato a settembre il processo di direct listing e dal 22 settembre \u00e8 quotata sul listino Euronext Growth. La societ\u00e0 sviluppa tecnologie innovative nell\u2019ambito delle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-20T09:33:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/12\/Orlando-Taddeo-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/\",\"name\":\"Airtime si rafforza e lancia il \\\"Piano USA 2023\\\": obiettivo crescere nei prossimi 24 mesi sul mercato americano -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/12\/Orlando-Taddeo-2.jpeg\",\"datePublished\":\"2021-12-20T09:33:51+00:00\",\"dateModified\":\"2021-12-20T09:33:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/12\/Orlando-Taddeo-2.jpeg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/12\/Orlando-Taddeo-2.jpeg\",\"width\":1170,\"height\":820,\"caption\":\"Orlando Taddeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Airtime si rafforza e lancia il &#8220;Piano USA 2023&#8221;: obiettivo crescere nei prossimi 24 mesi sul mercato americano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Airtime si rafforza e lancia il \"Piano USA 2023\": obiettivo crescere nei prossimi 24 mesi sul mercato americano -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/","og_locale":"it_IT","og_type":"article","og_title":"Airtime si rafforza e lancia il \"Piano USA 2023\": obiettivo crescere nei prossimi 24 mesi sul mercato americano -","og_description":"Rafforzare nei prossimi ventiquattro mesi la presenza su tutto il territorio americano: nasce con questo obiettivo il &#8220;Piano USA 2023&#8221; di Airtime Partecipazioni S.p.A., player attivo nel fintech, che ha completato a settembre il processo di direct listing e dal 22 settembre \u00e8 quotata sul listino Euronext Growth. La societ\u00e0 sviluppa tecnologie innovative nell\u2019ambito delle [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2021-12-20T09:33:51+00:00","og_image":[{"width":1170,"height":820,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/12\/Orlando-Taddeo-2.jpeg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/","name":"Airtime si rafforza e lancia il \"Piano USA 2023\": obiettivo crescere nei prossimi 24 mesi sul mercato americano -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/12\/Orlando-Taddeo-2.jpeg","datePublished":"2021-12-20T09:33:51+00:00","dateModified":"2021-12-20T09:33:51+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/12\/Orlando-Taddeo-2.jpeg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/12\/Orlando-Taddeo-2.jpeg","width":1170,"height":820,"caption":"Orlando Taddeo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/airtime-si-rafforza-e-lancia-il-piano-usa-2023-obiettivo-crescere-nei-prossimi-24-mesi-sul-mercato-americano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Airtime si rafforza e lancia il &#8220;Piano USA 2023&#8221;: obiettivo crescere nei prossimi 24 mesi sul mercato americano"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6454"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=6454"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6454\/revisions"}],"predecessor-version":[{"id":6456,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6454\/revisions\/6456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/6455"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=6454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=6454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=6454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}