{"id":6685,"date":"2022-04-13T10:58:42","date_gmt":"2022-04-13T08:58:42","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=6685"},"modified":"2022-04-13T10:58:42","modified_gmt":"2022-04-13T08:58:42","slug":"sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/","title":{"rendered":"Sanzioni pos, Confcommercio: &#8220;Non giova ai processi di modernizzazione del sistema pagamenti&#8221;"},"content":{"rendered":"<p>La diffusione dei pagamenti elettronici va perseguita mettendo in campo scelte decise di abbattimento delle commissioni e dei costi a carico di consumatori ed imprese &#8211; a partire dal potenziamento dello strumento del credito d\u2019imposta sulle commissioni pagate dall\u2019esercente &#8211; e prevedendo la gratuit\u00e0 dei cosiddetti micropagamenti.<\/p>\n<p>Puntare asimmetricamente sulle sanzioni non giova ai processi di modernizzazione del sistema dei pagamenti: processi, peraltro, gi\u00e0 in pieno sviluppo: cos\u00ec Confcommercio commenta la notizia dell\u2019anticipazione dal 2023 al prossimo mese di giugno dell\u2019entrata in vigore della multa a carico degli esercenti per la mancata accettazione di pagamenti effettuati attraverso carte di credito e di debito.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La diffusione dei pagamenti elettronici va perseguita mettendo in campo scelte decise di abbattimento delle commissioni e dei costi a carico di consumatori ed imprese &#8211; a partire dal potenziamento dello strumento del credito d\u2019imposta sulle commissioni pagate dall\u2019esercente &#8211; e prevedendo la gratuit\u00e0 dei cosiddetti micropagamenti. Puntare asimmetricamente sulle sanzioni non giova ai processi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6686,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sanzioni pos, Confcommercio: &quot;Non giova ai processi di modernizzazione del sistema pagamenti&quot; -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sanzioni pos, Confcommercio: &quot;Non giova ai processi di modernizzazione del sistema pagamenti&quot; -\" \/>\n<meta property=\"og:description\" content=\"La diffusione dei pagamenti elettronici va perseguita mettendo in campo scelte decise di abbattimento delle commissioni e dei costi a carico di consumatori ed imprese &#8211; a partire dal potenziamento dello strumento del credito d\u2019imposta sulle commissioni pagate dall\u2019esercente &#8211; e prevedendo la gratuit\u00e0 dei cosiddetti micropagamenti. Puntare asimmetricamente sulle sanzioni non giova ai processi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-13T08:58:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2022\/04\/Schermata-2022-04-13-alle-10.58.28.png\" \/>\n\t<meta property=\"og:image:width\" content=\"456\" \/>\n\t<meta property=\"og:image:height\" content=\"255\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/\",\"name\":\"Sanzioni pos, Confcommercio: \\\"Non giova ai processi di modernizzazione del sistema pagamenti\\\" -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2022\/04\/Schermata-2022-04-13-alle-10.58.28.png\",\"datePublished\":\"2022-04-13T08:58:42+00:00\",\"dateModified\":\"2022-04-13T08:58:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2022\/04\/Schermata-2022-04-13-alle-10.58.28.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2022\/04\/Schermata-2022-04-13-alle-10.58.28.png\",\"width\":456,\"height\":255},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sanzioni pos, Confcommercio: &#8220;Non giova ai processi di modernizzazione del sistema pagamenti&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sanzioni pos, Confcommercio: \"Non giova ai processi di modernizzazione del sistema pagamenti\" -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/","og_locale":"it_IT","og_type":"article","og_title":"Sanzioni pos, Confcommercio: \"Non giova ai processi di modernizzazione del sistema pagamenti\" -","og_description":"La diffusione dei pagamenti elettronici va perseguita mettendo in campo scelte decise di abbattimento delle commissioni e dei costi a carico di consumatori ed imprese &#8211; a partire dal potenziamento dello strumento del credito d\u2019imposta sulle commissioni pagate dall\u2019esercente &#8211; e prevedendo la gratuit\u00e0 dei cosiddetti micropagamenti. Puntare asimmetricamente sulle sanzioni non giova ai processi [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2022-04-13T08:58:42+00:00","og_image":[{"width":456,"height":255,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2022\/04\/Schermata-2022-04-13-alle-10.58.28.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/","name":"Sanzioni pos, Confcommercio: \"Non giova ai processi di modernizzazione del sistema pagamenti\" -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2022\/04\/Schermata-2022-04-13-alle-10.58.28.png","datePublished":"2022-04-13T08:58:42+00:00","dateModified":"2022-04-13T08:58:42+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2022\/04\/Schermata-2022-04-13-alle-10.58.28.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2022\/04\/Schermata-2022-04-13-alle-10.58.28.png","width":456,"height":255},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/sanzioni-pos-confcommercio-non-giova-ai-processi-di-modernizzazione-del-sistema-pagamenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Sanzioni pos, Confcommercio: &#8220;Non giova ai processi di modernizzazione del sistema pagamenti&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6685"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=6685"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6685\/revisions"}],"predecessor-version":[{"id":6687,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6685\/revisions\/6687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/6686"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=6685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=6685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=6685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}