{"id":6921,"date":"2022-10-19T18:31:30","date_gmt":"2022-10-19T16:31:30","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=6921"},"modified":"2022-10-19T18:31:30","modified_gmt":"2022-10-19T16:31:30","slug":"inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/","title":{"rendered":"Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale"},"content":{"rendered":"<p class=\"xmprfx_MsoNormal\">Lievita del +300% il prezzo medio di frutta e verdura nel percorso dal campo allo scaffale della Grande distribuzione organizzata. Secondo <b>Cia-Agricoltori Italiani l\u2019inflazione al galoppo sta creando forti squilibri lungo la filiera dei prodotti agricoli freschi<\/b>. Rilevanti le ripercussioni sui consumi di ortofrutta nelle famiglie, che registra una variazione del\u00a0-10% negli ultimi 12 mesi.<\/p>\n<p class=\"xmprfx_MsoNormal\">Ma \u00e8 anche allarme deflazione per gli agricoltori, che si vedono riconosciuti prezzi troppo bassi rispetto ai forti aumenti dei costi di produzione. Secondo l\u2019analisi Cia, in cima alla classifica del divario origine\/scaffale c\u2019\u00e8 l\u2019<b>uva da tavola<\/b> pagata 0,42 euro al chilo mentre sui banchi di vendita il prezzo va a quasi 3 euro al chilo<b> (+574%), <\/b>le<b> mele golden (+442%) <\/b>dagli 0,43 del campo ai 2,33 euro\/kg al consumo, mentre sul terzo scalino del podio la<b> melanzana tonda (+299%) <\/b>da 0,86 a 3,43 euro\/kg.<b> <\/b>Seguono le<b> pere williams (+293%) <\/b>da 0,71 a 2,79 euro\/kg,<b> i finocchi (+280%) <\/b>da 0,88 a 3,34 euro\/kg,<b> la lattuga romana (+263%) <\/b>da 0,82 a 3 euro\/kg,<b> <\/b>i <b>cavolfiori (+155%) <\/b>da 1,11 a 2,83 euro\/kg e la<b> zucchina scura (+125%), <\/b>che arriva sullo scaffale a 3,55 euro\/kg partendo dagli 1,58 euro dell\u2019azienda agricola<b>. <\/b><\/p>\n<p class=\"xmprfx_MsoNormal\">Per Cia, nella catena del valore alimentare a perdere sono, dunque, sempre gli agricoltori. Se il valore aggiunto agricolo \u00e8 il saldo tra la produzione e i consumi intermedi, sar\u00e0 sempre pi\u00f9 difficile per i produttori continuare a coltivare la propria terra. L\u2019ortofrutta italiana sconta ancora un forte gap infrastrutturale,<b>\u00a0<\/b>con criticit\u00e0 nella logistica e nelle fasi di stoccaggio e distribuzione. <b>Cia ricorda che solo per remunerare i costi di trasporto e distribuzione viene destinato il 41% del prezzo pagato dal consumatore finale<\/b>. Per riequilibrare la catena del valore e potenziare il mercato interno, occorrono dunque una maggiore aggregazione fra produttori e un \u201cpatto di sistema\u201d pi\u00f9 equo, moderno ed efficiente con tutti i soggetti del sistema ortofrutticolo, utile anche per rispondere alle sfide economiche e ambientali\u00a0legate al Green Deal europeo, che richiedono sempre maggiori standard di sostenibilit\u00e0.<\/p>\n<p class=\"xmprfx_MsoNormal\">\n","protected":false},"excerpt":{"rendered":"<p>Lievita del +300% il prezzo medio di frutta e verdura nel percorso dal campo allo scaffale della Grande distribuzione organizzata. Secondo Cia-Agricoltori Italiani l\u2019inflazione al galoppo sta creando forti squilibri lungo la filiera dei prodotti agricoli freschi. Rilevanti le ripercussioni sui consumi di ortofrutta nelle famiglie, che registra una variazione del\u00a0-10% negli ultimi 12 mesi. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5108,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale -\" \/>\n<meta property=\"og:description\" content=\"Lievita del +300% il prezzo medio di frutta e verdura nel percorso dal campo allo scaffale della Grande distribuzione organizzata. Secondo Cia-Agricoltori Italiani l\u2019inflazione al galoppo sta creando forti squilibri lungo la filiera dei prodotti agricoli freschi. Rilevanti le ripercussioni sui consumi di ortofrutta nelle famiglie, che registra una variazione del\u00a0-10% negli ultimi 12 mesi. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T16:31:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.45.09-1024x552.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/\",\"name\":\"Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.45.09.png\",\"datePublished\":\"2022-10-19T16:31:30+00:00\",\"dateModified\":\"2022-10-19T16:31:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.45.09.png\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.45.09.png\",\"width\":1346,\"height\":726},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/","og_locale":"it_IT","og_type":"article","og_title":"Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale -","og_description":"Lievita del +300% il prezzo medio di frutta e verdura nel percorso dal campo allo scaffale della Grande distribuzione organizzata. Secondo Cia-Agricoltori Italiani l\u2019inflazione al galoppo sta creando forti squilibri lungo la filiera dei prodotti agricoli freschi. Rilevanti le ripercussioni sui consumi di ortofrutta nelle famiglie, che registra una variazione del\u00a0-10% negli ultimi 12 mesi. [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2022-10-19T16:31:30+00:00","og_image":[{"width":1024,"height":552,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.45.09-1024x552.png","type":"image\/png"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/","name":"Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.45.09.png","datePublished":"2022-10-19T16:31:30+00:00","dateModified":"2022-10-19T16:31:30+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.45.09.png","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2021\/01\/Schermata-2021-01-15-alle-10.45.09.png","width":1346,"height":726},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/inflazione-cia-frutta-e-verdura-300-dal-campo-allo-scaffale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Inflazione: Cia, frutta e verdura +300% dal campo allo scaffale"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6921"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=6921"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6921\/revisions"}],"predecessor-version":[{"id":6922,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6921\/revisions\/6922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/5108"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=6921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=6921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=6921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}