{"id":6961,"date":"2022-11-24T17:15:31","date_gmt":"2022-11-24T16:15:31","guid":{"rendered":"http:\/\/www.italiaeconomiaonline.it\/web\/?p=6961"},"modified":"2022-11-24T17:15:31","modified_gmt":"2022-11-24T16:15:31","slug":"confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/","title":{"rendered":"Confcommercio Milano: 155 milioni di euro  nell\u2019online per il Black Friday"},"content":{"rendered":"<p>In crescita a Milano, Monza Brianza, Lodi, la spesa online per il Black Friday: 155 milioni di euro (acquisto dei beni) con un incremento dell\u201911% rispetto al 2021. Lo stima l\u2019Ufficio Studi di Confcommercio Milano, Lodi, Monza e Brianza*. Ed \u00e8 in leggero aumento anche la quota delle vendite del Black Friday sul complesso di quelle del Natale: 11,9% (contro l\u201911,3% dello scorso anno).<\/p>\n<p>Dall\u2019indagine di Confcommercio MiLoMb sull\u2019orientamento delle imprese (334 risposte, il 66% da Milano e area metropolitana &#8211; dati elaborati dall\u2019Ufficio Studi) nel dettaglio non alimentare il 40% delle imprese effettua sconti per il Black Friday con uno sconto medio del 24% (del 17%, invece, nei servizi). Nel dettaglio non alimentare il 45% delle imprese offre un servizio di pagamento rateizzabile.<\/p>\n<p>Per il periodo natalizio il 60% delle imprese non prevede cali di fatturato rispetto allo scorso anno: il 42% ritiene rester\u00e0 immutato, il 18% stima un incremento. Pi\u00f9 cauto il 40% delle imprese con una previsione di lievi decrementi per oltre la met\u00e0.<\/p>\n<p>\u201cGli sconti del Black Friday sono di fatto gi\u00e0 avviati da tempo e non si limitano a quest\u2019ultimo venerd\u00ec di novembre \u2013 afferma Marco Barbieri, segretario generale di Confcommercio Milano, Lodi, Monza e Brianza \u2013 E, guardando al Natale, la maggioranza delle imprese ha prospettive moderatamente ottimistiche. Le incognite inflazione e caro energia certo pesano sulle valutazioni. Contro i rincari in bolletta \u00e8 importante il credito d\u2019imposta, ma anche la possibilit\u00e0 di avere ristori\u201d (segnalata da tre imprese su quattro).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In crescita a Milano, Monza Brianza, Lodi, la spesa online per il Black Friday: 155 milioni di euro (acquisto dei beni) con un incremento dell\u201911% rispetto al 2021. Lo stima l\u2019Ufficio Studi di Confcommercio Milano, Lodi, Monza e Brianza*. Ed \u00e8 in leggero aumento anche la quota delle vendite del Black Friday sul complesso di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1232,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[612],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confcommercio Milano: 155 milioni di euro nell\u2019online per il Black Friday -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confcommercio Milano: 155 milioni di euro nell\u2019online per il Black Friday -\" \/>\n<meta property=\"og:description\" content=\"In crescita a Milano, Monza Brianza, Lodi, la spesa online per il Black Friday: 155 milioni di euro (acquisto dei beni) con un incremento dell\u201911% rispetto al 2021. Lo stima l\u2019Ufficio Studi di Confcommercio Milano, Lodi, Monza e Brianza*. Ed \u00e8 in leggero aumento anche la quota delle vendite del Black Friday sul complesso di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T16:15:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/ecommerce-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"411\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/\",\"name\":\"Confcommercio Milano: 155 milioni di euro nell\u2019online per il Black Friday -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/ecommerce-.jpg\",\"datePublished\":\"2022-11-24T16:15:31+00:00\",\"dateModified\":\"2022-11-24T16:15:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/ecommerce-.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/ecommerce-.jpg\",\"width\":960,\"height\":411},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confcommercio Milano: 155 milioni di euro nell\u2019online per il Black Friday\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confcommercio Milano: 155 milioni di euro nell\u2019online per il Black Friday -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/","og_locale":"it_IT","og_type":"article","og_title":"Confcommercio Milano: 155 milioni di euro nell\u2019online per il Black Friday -","og_description":"In crescita a Milano, Monza Brianza, Lodi, la spesa online per il Black Friday: 155 milioni di euro (acquisto dei beni) con un incremento dell\u201911% rispetto al 2021. Lo stima l\u2019Ufficio Studi di Confcommercio Milano, Lodi, Monza e Brianza*. Ed \u00e8 in leggero aumento anche la quota delle vendite del Black Friday sul complesso di [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2022-11-24T16:15:31+00:00","og_image":[{"width":960,"height":411,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/ecommerce-.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/","name":"Confcommercio Milano: 155 milioni di euro nell\u2019online per il Black Friday -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/ecommerce-.jpg","datePublished":"2022-11-24T16:15:31+00:00","dateModified":"2022-11-24T16:15:31+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/ecommerce-.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/07\/ecommerce-.jpg","width":960,"height":411},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-milano-155-milioni-di-euro-nellonline-per-il-black-friday\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Confcommercio Milano: 155 milioni di euro nell\u2019online per il Black Friday"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6961"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=6961"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6961\/revisions"}],"predecessor-version":[{"id":6962,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/6961\/revisions\/6962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1232"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=6961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=6961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=6961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}