{"id":7135,"date":"2023-04-05T15:45:23","date_gmt":"2023-04-05T13:45:23","guid":{"rendered":"https:\/\/www.italiaeconomiaonline.it\/web\/?p=7135"},"modified":"2023-04-05T15:45:23","modified_gmt":"2023-04-05T13:45:23","slug":"olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/","title":{"rendered":"Olio di Calabria emoziona al Vinitaly ed a Sol&#038;Agrifoof"},"content":{"rendered":"<div class=\"application-pane\">\n<div class=\"main-pane\">\n<div id=\"application-stack\" class=\"dijitContainer dijitStackContainer dijitLayoutContainer\" dir=\"ltr\" role=\"tabpanel\">\n<div id=\"webmail-page\" class=\"main-page dijitContentPane dijitStackContainer-child dijitStackContainer-dijitContentPane dijitVisible menu-not-pinned is-next is-previous\" role=\"group\">\n<div class=\"main-page-center-pane\">\n<div class=\"main-page-pane-with-toolbar\">\n<div class=\"main-content\">\n<div id=\"uiLogic_util_StackContainer_0\" class=\"content-stack-container dijitContainer dijitStackContainer dijitLayoutContainer leading-active componentVisible\" dir=\"ltr\" role=\"tabpanel\">\n<div id=\"uiLogic_webmail_WebmailFoldersManager_0\" class=\"webmailfoldersmanager messages-compose-compofeedback-stack dijitContainer dijitStackContainer dijitLayoutContainer dijitStackContainer-child dijitStackContainer-dijitStackContainer dijitVisible componentVisible\" dir=\"ltr\" role=\"tabpanel\">\n<div id=\"dijit_layout_BorderContainer_0\" class=\"trailing-1 messages-container dijitContainer dijitBorderContainer dijitStackContainer-child dijitStackContainer-dijitBorderContainer dijitVisible componentVisible center-active trailing-active\" dir=\"ltr\" lang=\"\">\n<div id=\"dijit_layout_ContentPane_0\" class=\"dijitContentPane dijitBorderContainer-child dijitBorderContainer-dijitContentPane dijitBorderContainerPane dijitContentPaneSingleChild\" dir=\"ltr\" lang=\"\" role=\"group\">\n<div id=\"xandmail_widget_layout_RelativeBorderContainer_0\" class=\"dijitContainer dijitBorderContainer\" dir=\"ltr\" lang=\"\">\n<div id=\"dijit_layout_StackContainer_0\" class=\"dijitContainer dijitStackContainer dijitLayoutContainer dijitBorderContainer-child dijitBorderContainer-dijitStackContainer dijitBorderContainerPane\" dir=\"ltr\" lang=\"\" role=\"tabpanel\">\n<div id=\"dijit_layout_ContentPane_4\" class=\"component-page item-view webmail-view trailing-1 webmail-view-page dijitContentPane dijitStackContainer-child dijitStackContainer-dijitContentPane dijitVisible dijitContentPaneSingleChild\" dir=\"ltr\" lang=\"\" role=\"group\">\n<div id=\"dijit_layout_BorderContainer_4\" class=\"message dijitContainer dijitBorderContainer\" dir=\"ltr\">\n<div id=\"dijit_layout_ContentPane_15\" class=\"content dijitContentPane dijitBorderContainer-child dijitBorderContainer-dijitContentPane dijitBorderContainerPane\" dir=\"ltr\" role=\"group\">\n<div class=\"message-section\">\n<div class=\"content-message\">\n<div class=\"text msg-view-text\" role=\"text\">\n<div class=\"msg-view-text-cnt\">\n<div class=\"xam_msg_class\">\n<div dir=\"auto\">\n<div dir=\"ltr\">\n<p>L&#8217;olio calabrese regala emozioni. Punta sempre pi\u00f9 sul binomio alimentazione e salute, spingendo verso una qualit\u00e0 esclusiva. Durante la seconda giornata di\u00a0<strong>Sol&amp;Agrifood<\/strong>\u00a0&#8211; la fiera btob dell\u2019eccellenza agroalimentare che si svolge a\u00a0<strong>Verona fino al 5 aprile<\/strong>\u00a0in contemporanea con Vinitaly &#8211; si \u00e8 tenuto l\u2019incontro \u201cGli oli extravergine calabresi nel panorama italiano\u201d organizzato dal\u00a0<strong>Consorzio di Tutela e Valorizzazione Olio di Calabria IGP<\/strong>, in collaborazione con la\u00a0<strong>Regione Calabria.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La tavola rotonda, moderata dal giornalista\u00a0<strong>Claudio Brachino<\/strong>, \u00e8 stata aperta dal presidente del Consorzio Olio di Calabria IGP<strong>\u00a0Massimino Magliocchi<\/strong>, che ha tenuto a sottolineare il ruolo di primo piano che ricopre l\u2019olio extravergine d\u2019oliva nella tutela della salute: \u00abL\u2019attivit\u00e0 del Consorzio si sta concentrando sul far conoscere non solo la bont\u00e0, ma anche le propriet\u00e0 salutistiche intrinseche del nostro olio. Lo dimostrano le numerose iniziative che stiamo portando avanti, prima fra tutte quelle nate dalla partnership con la\u00a0<strong>Lega Italiana per la Lotta contro i Tumori<\/strong>. Siamo fortemente convinti che l\u2019olio extravergine di oliva sia sinonimo di salute e in quest\u2019ottica abbiamo scelto come testimonial del nostro Consorzio il campione calabrese di tuffi\u00a0<strong>Giovanni Tocci<\/strong>, poich\u00e9 lo sport deve andare di pari passo con la corretta alimentazione affinch\u00e9 il nostro benessere psico-fisico sia tutelato\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>Il tema della salute \u00e8 stato approfondito da\u00a0<strong>Francesco Vaia<\/strong>, direttore generale dell\u2019Istituto Nazionale Malattie Infettive Spallanzani, il quale nel suo intervento ha fatto un appello al governo per aprire un tavolo che riunisca diversi Ministeri, quello dell\u2019Istruzione, quello della Salute e quello dell\u2019Agricoltura per lavorare in sinergia nell\u2019intento comune di far tornare la salute dei cittadini e la prevenzione al centro.<\/p>\n<p>\u00abCredo sia fondamentale \u2013 ha dichiarato Vaia &#8211; ricominciare a investire in prevenzione, partendo dalle scuole e insegnando ai giovani l\u2019educazione alla buona salute. Il governo sta puntando molto sul rilancio dello stile di vita italiano, uno stile di vita sano, caratterizzato da una dieta varia ed equilibrata, come quella mediterranea, dove l\u2019olio extravergine di oliva occupa un posto d\u2019onore. I suoi benefici per la salute derivano principalmente dalla sua composizione, fatta dal 99% di grassi, la maggior parte dei quali (tra il 68% e l\u201983%) sono buoni, monoinsaturi, utili a contenere i livelli di colesterolo nel sangue. L\u2019olio \u00e8 anche ricco di polifenoli che hanno un\u2019importante azione antiossidante e antinfiammatoria\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>In rappresentanza delle Istituzioni e a illustrare i recenti sviluppi della produzione olivicola calabrese sono intervenuti\u00a0<strong>Gianluca Gallo<\/strong>, Assessore alle Politiche Agricole e allo Sviluppo Agroalimentare della Regione Calabria, e\u00a0<strong>Giacomo Giovinazzo<\/strong>, direttore generale del dipartimento Agricoltura della Regione Calabria.<\/p>\n<p>\u00abIn passato &#8211; ha chiosato l\u2019Assessore Gallo &#8211; l\u2019ulivo \u00e8 stato un vero e proprio ascensore sociale per noi calabresi e anche oggi potrebbe esserlo, purch\u00e9 i produttori abbiano un\u2019unica ambizione, quella della produzione di qualit\u00e0. In questa direzione \u00e8 stato creato un bando che uscir\u00e0 a breve per il rinnovo dei frantoi che prevedr\u00e0 anche la partecipazione a corsi di formazione per il miglioramento della qualit\u00e0. In Calabria possediamo una straordinaria biodiversit\u00e0, tante variet\u00e0 autoctone sulle quali puntare, per questo motivo stiamo ideando insieme al CREA (Consiglio per la Ricerca in Agricoltura e l\u2019Analisi dell\u2019Economia Agraria) un piano olivicolo regionale, un programma regolatorio della nostra olivicoltura che ci auspichiamo generi degli investimenti per il rinnovo varietale. Un altro importante obiettivo su quale ci stiamo concentrando \u00e8 quello del reperimento dei mercati che possano recepire i nostri prodotti di qualit\u00e0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abCon 21 milioni di ulivi coltivati su una superficie di 184 mila ettari, l\u2019olio ricopre un ruolo fondamentale nella storia e nella cultura calabrese. Come dipartimento stiamo cercando di tutelare e proteggere gli uliveti calabresi, mantenendoli all\u2019interno di un sistema produttivo, poich\u00e9 se il prodotto olio non viene valorizzato, il rischio \u00e8 che ci sia un abbondano della sua coltivazione, che sarebbe una perdita sotto diversi punti di vista, sia quello economico, ma anche quello del nostro patrimonio storico e culturale. Incontri come questo si rivelano quindi preziosi per promuovere le propriet\u00e0 dell\u2019olio e ridare valore a delle produzioni che negli ultimi anni sono state trascurate\u00bb ha concluso Giovinazzo.<\/p>\n<p>Al termine dell&#8217;incontro, i gelati sapientemente preparati con gli ingredienti messi a disposizione dai Consorzi del limone di Rocca imperiale, del Bergamotto di Reggio Calabria, della Liquirizia di Calabria e delle Clementine. Prima, invece, lo chef Armando Codispoti ha deliziato i presenti con un piatto unico dai sapori calabresi.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"msg-view-attach-preview\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"uiLogic_webmail__view_ListReceipt_0\" class=\"pec-receipts-section light-list spaced-view webmail-inbox-list\" dir=\"ltr\">\n<div><\/div>\n<\/div>\n<\/div>\n<div id=\"dijit_layout_ContentPane_15_splitter\" class=\"dijitGutter dijitGutterV\" role=\"presentation\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"dijit_layout_StackContainer_0_splitter\" class=\"dijitSplitter dijitSplitterV\" role=\"separator\">\n<div class=\"dijitSplitterThumb\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"dijit_layout_ContentPane_0_splitter\" class=\"dijitGutter dijitGutterV\" role=\"presentation\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"xamGlobalDock\" class=\"xamDock\" dir=\"ltr\">\n<div class=\"docking-pane-container\"><\/div>\n<div class=\"summary-pane-container\"><\/div>\n<\/div>\n<\/div>\n<div class=\"dijitPopup\" role=\"presentation\">\n<div id=\"dijit_TooltipDialog_0\" class=\"user-ffn-tooltip-dialog dijitTooltipABRight dijitTooltipDialog\" dir=\"ltr\" lang=\"\" role=\"presentation\">\n<div class=\"dijitTooltipContainer\" role=\"presentation\">\n<div class=\"dijitTooltipContents dijitTooltipFocusNode\" tabindex=\"-1\" role=\"dialog\">\n<div class=\"user-menu\">\n<div class=\"user-menu-title\">\n<div id=\"uiLogic_util_UserAvatarPicker_0\" class=\"avatar-picker-cnt avatar-picker default-avatar avatar-picker-text\" dir=\"ltr\" lang=\"\">\n<div class=\"avatar-picker-photo-cnt\">\n<div class=\"avatar-picker-photo\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"user-menu-title-cnt flex-column\">\n<div class=\"flex\">\n<div class=\"user-menu-emailffn-cnt flex-column\">\n<div class=\"user-menu-ffn\"><\/div>\n<div class=\"user-menu-email-cnt\">\n<div class=\"user-menu-email\"><\/div>\n<div class=\"user-pecplus\"><\/div>\n<\/div>\n<\/div>\n<div class=\"user-menu-link link\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"dijitPopup\" role=\"presentation\">\n<table id=\"uiLogic_webmail_selection_MessageMenu_0\" class=\"dijit dijitMenu dijitMenuPassive dijitReset dijitMenuTable\" tabindex=\"-1\" role=\"menu\" cellspacing=\"0\">\n<tbody class=\"dijitReset\">\n<tr id=\"dijit_MenuItem_33\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_33_text dijit_MenuItem_33_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_33_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_34\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_34_text dijit_MenuItem_34_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_34_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_35\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_35_text dijit_MenuItem_35_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_35_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_36\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_36_text dijit_MenuItem_36_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_36_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuSeparator_5\" class=\"dijitMenuSeparator\">\n<td class=\"dijitMenuSeparatorIconCell\">\n<div class=\"dijitMenuSeparatorTop\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<td class=\"dijitMenuSeparatorLabelCell\" colspan=\"3\">\n<div class=\"dijitMenuSeparatorTop dijitMenuSeparatorLabel\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_37\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_37_text dijit_MenuItem_37_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_37_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_PopupMenuItem_1\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_PopupMenuItem_1_text dijit_PopupMenuItem_1_accel\" aria-haspopup=\"true\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_PopupMenuItem_1_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_44\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_44_text dijit_MenuItem_44_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_44_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_45\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_45_text dijit_MenuItem_45_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_45_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_46\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_46_text dijit_MenuItem_46_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_46_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_47\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_47_text dijit_MenuItem_47_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_47_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuSeparator_7\" class=\"dijitMenuSeparator\">\n<td class=\"dijitMenuSeparatorIconCell\">\n<div class=\"dijitMenuSeparatorTop\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<td class=\"dijitMenuSeparatorLabelCell\" colspan=\"3\">\n<div class=\"dijitMenuSeparatorTop dijitMenuSeparatorLabel\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_PopupMenuItem_2\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_PopupMenuItem_2_text dijit_PopupMenuItem_2_accel\" aria-haspopup=\"true\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_PopupMenuItem_2_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_52\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_52_text dijit_MenuItem_52_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_52_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuSeparator_8\" class=\"dijitMenuSeparator\">\n<td class=\"dijitMenuSeparatorIconCell\">\n<div class=\"dijitMenuSeparatorTop\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<td class=\"dijitMenuSeparatorLabelCell\" colspan=\"3\">\n<div class=\"dijitMenuSeparatorTop dijitMenuSeparatorLabel\"><\/div>\n<div class=\"dijitMenuSeparatorBottom\"><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_53\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_53_text dijit_MenuItem_53_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_53_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<tr id=\"dijit_MenuItem_54\" class=\"dijitReset dijitMenuItem\" tabindex=\"-1\" role=\"menuitem\" aria-labelledby=\"dijit_MenuItem_54_text dijit_MenuItem_54_accel\">\n<td class=\"dijitReset dijitMenuItemIconCell\" role=\"presentation\"><img decoding=\"async\" class=\"dijitIcon dijitMenuItemIcon\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/td>\n<td id=\"dijit_MenuItem_54_text\" class=\"dijitReset dijitMenuItemLabel\" colspan=\"2\"><\/td>\n<td class=\"dijitReset dijitMenuArrowCell\" role=\"presentation\">\n<div><img decoding=\"async\" class=\"dijitMenuExpand\" src=\"https:\/\/webmail.aruba.it\/smart\/javascript\/release\/dojo\/dojo\/resources\/blank.gif\" alt=\"\" \/><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;olio calabrese regala emozioni. Punta sempre pi\u00f9 sul binomio alimentazione e salute, spingendo verso una qualit\u00e0 esclusiva. Durante la seconda giornata di\u00a0Sol&amp;Agrifood\u00a0&#8211; la fiera btob dell\u2019eccellenza agroalimentare che si svolge a\u00a0Verona fino al 5 aprile\u00a0in contemporanea con Vinitaly &#8211; si \u00e8 tenuto l\u2019incontro \u201cGli oli extravergine calabresi nel panorama italiano\u201d organizzato dal\u00a0Consorzio di Tutela e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Olio di Calabria emoziona al Vinitaly ed a Sol&amp;Agrifoof -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olio di Calabria emoziona al Vinitaly ed a Sol&amp;Agrifoof -\" \/>\n<meta property=\"og:description\" content=\"L&#8217;olio calabrese regala emozioni. Punta sempre pi\u00f9 sul binomio alimentazione e salute, spingendo verso una qualit\u00e0 esclusiva. Durante la seconda giornata di\u00a0Sol&amp;Agrifood\u00a0&#8211; la fiera btob dell\u2019eccellenza agroalimentare che si svolge a\u00a0Verona fino al 5 aprile\u00a0in contemporanea con Vinitaly &#8211; si \u00e8 tenuto l\u2019incontro \u201cGli oli extravergine calabresi nel panorama italiano\u201d organizzato dal\u00a0Consorzio di Tutela e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-05T13:45:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/\",\"name\":\"Olio di Calabria emoziona al Vinitaly ed a Sol&Agrifoof -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"datePublished\":\"2023-04-05T13:45:23+00:00\",\"dateModified\":\"2023-04-05T13:45:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Olio di Calabria emoziona al Vinitaly ed a Sol&#038;Agrifoof\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olio di Calabria emoziona al Vinitaly ed a Sol&Agrifoof -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/","og_locale":"it_IT","og_type":"article","og_title":"Olio di Calabria emoziona al Vinitaly ed a Sol&Agrifoof -","og_description":"L&#8217;olio calabrese regala emozioni. Punta sempre pi\u00f9 sul binomio alimentazione e salute, spingendo verso una qualit\u00e0 esclusiva. Durante la seconda giornata di\u00a0Sol&amp;Agrifood\u00a0&#8211; la fiera btob dell\u2019eccellenza agroalimentare che si svolge a\u00a0Verona fino al 5 aprile\u00a0in contemporanea con Vinitaly &#8211; si \u00e8 tenuto l\u2019incontro \u201cGli oli extravergine calabresi nel panorama italiano\u201d organizzato dal\u00a0Consorzio di Tutela e [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2023-04-05T13:45:23+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/","name":"Olio di Calabria emoziona al Vinitaly ed a Sol&Agrifoof -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","datePublished":"2023-04-05T13:45:23+00:00","dateModified":"2023-04-05T13:45:23+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2018\/08\/olio_di_oliva.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/olio-di-calabria-emoziona-al-vinitaly-ed-a-solagrifoof\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Olio di Calabria emoziona al Vinitaly ed a Sol&#038;Agrifoof"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7135"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=7135"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7135\/revisions"}],"predecessor-version":[{"id":7136,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7135\/revisions\/7136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/187"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=7135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=7135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=7135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}