{"id":7141,"date":"2023-04-06T14:37:33","date_gmt":"2023-04-06T12:37:33","guid":{"rendered":"https:\/\/www.italiaeconomiaonline.it\/web\/?p=7141"},"modified":"2023-04-06T14:37:33","modified_gmt":"2023-04-06T12:37:33","slug":"confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/","title":{"rendered":"Confcommercio Lombardia: efficienza energetica e formazione  fondamentali per lo sviluppo del Terziario"},"content":{"rendered":"<p>Positivo il pacchetto di misure regionali in tema di sviluppo aziendale, attrazione degli investimenti ed efficienza energetica, per uno stanziamento complessivo di 210 milioni di euro.<\/p>\n<p>\u201c<i>Con questi importanti stanziamenti Regione Lombardia dimostra attenzione alle esigenze di innovazione e attrattivit\u00e0 del tessuto economico lombardo<\/i>\u00a0&#8211; dichiara il vicepresidente vicario di Confcommercio Lombardia\u00a0<b>Carlo Massoletti<\/b>\u00a0&#8211;\u00a0<i>In tema di sostenibilit\u00e0, in particolare, questa misura si aggiunge agli altri interventi regionali sul fronte dell\u2019efficientamento energetico, in grado di favorire la conciliazione tra attenzione all\u2019ambiente e sviluppo economico<\/i>\u201d.<\/p>\n<p>Da segnalare, inoltre, anche i 5 milioni messi a disposizione per la formazione green e digitale.<\/p>\n<p>\u201c<i>Una spinta importante\u00a0<\/i>\u2013 prosegue\u00a0<b>Massoletti<\/b>\u00a0&#8211;\u00a0<i>per incrementare le competenze su questi temi che permettono al Terziario di affrontare le sfide future, rispondendo anche alle mutate sensibilit\u00e0 di consumatori e turisti. Apprezzabile, dunque, l\u2019impegno del presidente Fontana e all\u2019assessore Guidesi che hanno colto le istanze delle imprese del Terziario volte ad una crescita sostenibile e sempre pi\u00f9 all\u2019avanguardia<\/i>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Positivo il pacchetto di misure regionali in tema di sviluppo aziendale, attrazione degli investimenti ed efficienza energetica, per uno stanziamento complessivo di 210 milioni di euro. \u201cCon questi importanti stanziamenti Regione Lombardia dimostra attenzione alle esigenze di innovazione e attrattivit\u00e0 del tessuto economico lombardo\u00a0&#8211; dichiara il vicepresidente vicario di Confcommercio Lombardia\u00a0Carlo Massoletti\u00a0&#8211;\u00a0In tema di sostenibilit\u00e0, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1782,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[612],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confcommercio Lombardia: efficienza energetica e formazione fondamentali per lo sviluppo del Terziario -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confcommercio Lombardia: efficienza energetica e formazione fondamentali per lo sviluppo del Terziario -\" \/>\n<meta property=\"og:description\" content=\"Positivo il pacchetto di misure regionali in tema di sviluppo aziendale, attrazione degli investimenti ed efficienza energetica, per uno stanziamento complessivo di 210 milioni di euro. \u201cCon questi importanti stanziamenti Regione Lombardia dimostra attenzione alle esigenze di innovazione e attrattivit\u00e0 del tessuto economico lombardo\u00a0&#8211; dichiara il vicepresidente vicario di Confcommercio Lombardia\u00a0Carlo Massoletti\u00a0&#8211;\u00a0In tema di sostenibilit\u00e0, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T12:37:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/\",\"name\":\"Confcommercio Lombardia: efficienza energetica e formazione fondamentali per lo sviluppo del Terziario -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg\",\"datePublished\":\"2023-04-06T12:37:33+00:00\",\"dateModified\":\"2023-04-06T12:37:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg\",\"width\":960,\"height\":685},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confcommercio Lombardia: efficienza energetica e formazione fondamentali per lo sviluppo del Terziario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confcommercio Lombardia: efficienza energetica e formazione fondamentali per lo sviluppo del Terziario -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/","og_locale":"it_IT","og_type":"article","og_title":"Confcommercio Lombardia: efficienza energetica e formazione fondamentali per lo sviluppo del Terziario -","og_description":"Positivo il pacchetto di misure regionali in tema di sviluppo aziendale, attrazione degli investimenti ed efficienza energetica, per uno stanziamento complessivo di 210 milioni di euro. \u201cCon questi importanti stanziamenti Regione Lombardia dimostra attenzione alle esigenze di innovazione e attrattivit\u00e0 del tessuto economico lombardo\u00a0&#8211; dichiara il vicepresidente vicario di Confcommercio Lombardia\u00a0Carlo Massoletti\u00a0&#8211;\u00a0In tema di sostenibilit\u00e0, [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2023-04-06T12:37:33+00:00","og_image":[{"width":960,"height":685,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/","name":"Confcommercio Lombardia: efficienza energetica e formazione fondamentali per lo sviluppo del Terziario -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg","datePublished":"2023-04-06T12:37:33+00:00","dateModified":"2023-04-06T12:37:33+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/09\/formazione.jpg","width":960,"height":685},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/confcommercio-lombardia-efficienza-energetica-e-formazione-fondamentali-per-lo-sviluppo-del-terziario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Confcommercio Lombardia: efficienza energetica e formazione fondamentali per lo sviluppo del Terziario"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7141"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=7141"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7141\/revisions"}],"predecessor-version":[{"id":7142,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7141\/revisions\/7142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1782"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=7141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=7141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=7141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}