{"id":7143,"date":"2023-04-07T11:31:34","date_gmt":"2023-04-07T09:31:34","guid":{"rendered":"https:\/\/www.italiaeconomiaonline.it\/web\/?p=7143"},"modified":"2023-04-07T11:31:34","modified_gmt":"2023-04-07T09:31:34","slug":"bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/","title":{"rendered":"BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia"},"content":{"rendered":"<p class=\"p5\">Si \u00e8 svolta ieri pomeriggio al BPER Banca Forum Monzani di Modena la cerimonia di consegna delle borse di studio Fondazione 150\u00b0 di BPER Banca.<\/p>\n<p class=\"p5\">Quest\u2019anno sono stati premiati 266 studenti provenienti da 42 province italiane che si sono distinti nel corso dell\u2019anno scolastico 2020-2021: 85 di loro hanno ricevuto un assegno da 700 euro, altri 181 un assegno da 500 euro. Un folto gruppo di premiati ha partecipato di persona all\u2019evento, che \u00e8 stato anche trasmesso in streaming.<\/p>\n<p class=\"p5\">Per BPER Banca sono intervenuti la Presidente <b>Flavia Mazzarella<\/b> e il Chief Human Resources Officer, <b>Giuseppe Corni<\/b>. Erano inoltre presenti <b>Alessandra Camporota<\/b>, Prefetto di Modena, <b>Maria Grazia Baracchi<\/b>, assessore all\u2019Istruzione del Comune di Modena e <b>Gianluca Marchi<\/b>, Pro Rettore vicario dell\u2019Universit\u00e0 degli Studi di Modena e Reggio Emilia.<\/p>\n<p class=\"p5\">Il Premio, giunto alla 56esima edizione, \u00e8 stato istituito nel 1967 in occasione del centenario della Banca Popolare di Modena e portato avanti negli anni, nel solco della tradizione, anche dopo la celebrazione, nel 2017, del 150\u00b0 anniversario della nascita della banca, diventata nel frattempo BPER Banca.<\/p>\n<p class=\"p5\">L\u2019iniziativa \u00e8 un\u2019ulteriore testimonianza dell\u2019attenzione che l\u2019Istituto riserva ai territori, con particolare riguardo al mondo della scuola, dell\u2019educazione e delle giovani generazioni.<\/p>\n<p class=\"p5\">Nel corso dell\u2019evento la Presidente <b>Flavia Mazzarella<\/b> ha affermato: \u201cBPER Banca \u00e8 sempre attenta a riconoscere il talento dei giovani, perch\u00e9 vuole contribuire all\u2019educazione delle nuove generazioni anche attraverso il sostegno al percorso scolastico e universitario per formare le persone e i professionisti di domani. Oggi \u00e8 un giorno speciale per noi e per questi studenti, perch\u00e9 vedono premiato il risultato del loro impegno e della competenza raggiunta: a loro vanno i nostri migliori complimenti e l\u2019augurio di poter realizzare i propri sogni. La Banca \u2013 ha aggiunto Mazzarella \u2013 porta avanti ormai per tradizione numerosi progetti per valorizzare il talento giovanile, in particolare con iniziative didattiche e partnership con Accademie, Universit\u00e0 e scuole. Una scelta fortemente voluta per offrire ai ragazzi maggiori opportunit\u00e0 in termini di istruzione, formazione e lavoro\u201d.<\/p>\n<p class=\"p5\">Il Chief Human Resources Officer,<b> Giuseppe Corni<\/b>, ha a sua volta dichiarato: \u201cLa nostra Banca cerca di sostenere il percorso umano e formativo dei giovani talenti, premiandoli per il loro impegno e per i risultati. Ma la finalit\u00e0 dell\u2019azione di BPER \u00e8 duplice, perch\u00e9 questi stessi giovani saranno i migliori professionisti di domani che verranno inseriti nelle nostre aziende: siamo certi, dunque, che l\u2019investimento sul valore umano e professionale di questi giovani talenti sia un\u2019azione che contribuir\u00e0 a creare valore per la societ\u00e0 nel tempo\u201d.<\/p>\n<p class=\"p4\">\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolta ieri pomeriggio al BPER Banca Forum Monzani di Modena la cerimonia di consegna delle borse di studio Fondazione 150\u00b0 di BPER Banca. Quest\u2019anno sono stati premiati 266 studenti provenienti da 42 province italiane che si sono distinti nel corso dell\u2019anno scolastico 2020-2021: 85 di loro hanno ricevuto un assegno da 700 euro, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7144,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia -\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 svolta ieri pomeriggio al BPER Banca Forum Monzani di Modena la cerimonia di consegna delle borse di studio Fondazione 150\u00b0 di BPER Banca. Quest\u2019anno sono stati premiati 266 studenti provenienti da 42 province italiane che si sono distinti nel corso dell\u2019anno scolastico 2020-2021: 85 di loro hanno ricevuto un assegno da 700 euro, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-07T09:31:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2023\/04\/BPER_Cerimonia-2023_Borse-di-studio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/\",\"name\":\"BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2023\/04\/BPER_Cerimonia-2023_Borse-di-studio.jpg\",\"datePublished\":\"2023-04-07T09:31:34+00:00\",\"dateModified\":\"2023-04-07T09:31:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2023\/04\/BPER_Cerimonia-2023_Borse-di-studio.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2023\/04\/BPER_Cerimonia-2023_Borse-di-studio.jpg\",\"width\":2016,\"height\":1344},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/","og_locale":"it_IT","og_type":"article","og_title":"BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia -","og_description":"Si \u00e8 svolta ieri pomeriggio al BPER Banca Forum Monzani di Modena la cerimonia di consegna delle borse di studio Fondazione 150\u00b0 di BPER Banca. Quest\u2019anno sono stati premiati 266 studenti provenienti da 42 province italiane che si sono distinti nel corso dell\u2019anno scolastico 2020-2021: 85 di loro hanno ricevuto un assegno da 700 euro, [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2023-04-07T09:31:34+00:00","og_image":[{"width":2016,"height":1344,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2023\/04\/BPER_Cerimonia-2023_Borse-di-studio.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/","name":"BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2023\/04\/BPER_Cerimonia-2023_Borse-di-studio.jpg","datePublished":"2023-04-07T09:31:34+00:00","dateModified":"2023-04-07T09:31:34+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2023\/04\/BPER_Cerimonia-2023_Borse-di-studio.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2023\/04\/BPER_Cerimonia-2023_Borse-di-studio.jpg","width":2016,"height":1344},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/bper-banca-266-borse-di-studio-a-giovani-meritevoli-di-tutta-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"BPER Banca, 266 borse di studio a giovani meritevoli di tutta Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7143"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=7143"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7143\/revisions"}],"predecessor-version":[{"id":7145,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7143\/revisions\/7145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/7144"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=7143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=7143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=7143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}