{"id":7999,"date":"2026-04-01T17:27:25","date_gmt":"2026-04-01T15:27:25","guid":{"rendered":"https:\/\/www.italiaeconomiaonline.it\/web\/?p=7999"},"modified":"2026-04-01T17:27:25","modified_gmt":"2026-04-01T15:27:25","slug":"tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio","status":"publish","type":"post","link":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/","title":{"rendered":"Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio"},"content":{"rendered":"<p style=\"font-weight: 400;\">A margine dell\u2019incontro presso il Ministero delle Imprese e del Made in Italy, Cia-Agricoltori Italiani ha ribadito l\u2019allarme per l\u2019agricoltura italiana, tra i comparti pi\u00f9 esposti alle crisi belliche ed energetiche. Italia ed Europa devono agire subito sia con il credito d\u2019imposta per il gasolio agricolo, come gi\u00e0 sollecitato da settimane, sia con un pacchetto di misure ad hoc dalla Commissione europea.<\/p>\n<p style=\"font-weight: 400;\">Pur apprezzando gli sforzi del governo sui temi del tavolo odierno, Cia chiede con forza una strategia strutturata per gestire la crisi e garantire tutele negli approvvigionamenti di materie prime strategiche. Il conflitto in Medio Oriente provoca rincari fino al 60% su gasolio e urea, fertilizzanti introvabili, turbolenze nei mercati di gas ed elettricit\u00e0: un impatto medio di decine di migliaia di euro per ogni impresa.<\/p>\n<p style=\"font-weight: 400;\">Non c\u2019\u00e8 pi\u00f9 tempo da perdere: gli agricoltori sono esausti e i 4 centesimi in meno sulle accise non bastano. Servono interventi incisi e risorse consistenti per preservare la sicurezza alimentare globale, evitando che aziende riducano la produzione o chiudano. Bisogna tutelare la sovranit\u00e0 del nostro Made in Italy agroalimentare, che senza cerealicoltura, zootecnia da latte e florovivaismo \u2013 filiere tra le pi\u00f9 sensibili \u2013 perde la sua essenza. Oggi, nei campi, nelle stalle e nelle serre, il nostro sistema agricolo nazionale \u00e8 sotto assedio.<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>A margine dell\u2019incontro presso il Ministero delle Imprese e del Made in Italy, Cia-Agricoltori Italiani ha ribadito l\u2019allarme per l\u2019agricoltura italiana, tra i comparti pi\u00f9 esposti alle crisi belliche ed energetiche. Italia ed Europa devono agire subito sia con il credito d\u2019imposta per il gasolio agricolo, come gi\u00e0 sollecitato da settimane, sia con un pacchetto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1039,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[537],"tags":[349,1907],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio -\" \/>\n<meta property=\"og:description\" content=\"A margine dell\u2019incontro presso il Ministero delle Imprese e del Made in Italy, Cia-Agricoltori Italiani ha ribadito l\u2019allarme per l\u2019agricoltura italiana, tra i comparti pi\u00f9 esposti alle crisi belliche ed energetiche. Italia ed Europa devono agire subito sia con il credito d\u2019imposta per il gasolio agricolo, come gi\u00e0 sollecitato da settimane, sia con un pacchetto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T15:27:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/biodiversita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"593\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ladyitaliaeconomia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ladyitaliaeconomia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/\",\"name\":\"Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio -\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/biodiversita.jpg\",\"datePublished\":\"2026-04-01T15:27:25+00:00\",\"dateModified\":\"2026-04-01T15:27:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#primaryimage\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/biodiversita.jpg\",\"contentUrl\":\"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/biodiversita.jpg\",\"width\":960,\"height\":593},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31\",\"name\":\"ladyitaliaeconomia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g\",\"caption\":\"ladyitaliaeconomia\"},\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/","og_locale":"it_IT","og_type":"article","og_title":"Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio -","og_description":"A margine dell\u2019incontro presso il Ministero delle Imprese e del Made in Italy, Cia-Agricoltori Italiani ha ribadito l\u2019allarme per l\u2019agricoltura italiana, tra i comparti pi\u00f9 esposti alle crisi belliche ed energetiche. Italia ed Europa devono agire subito sia con il credito d\u2019imposta per il gasolio agricolo, come gi\u00e0 sollecitato da settimane, sia con un pacchetto [&hellip;]","og_url":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/","og_site_name":"ItaliaEconomiaOnline","article_published_time":"2026-04-01T15:27:25+00:00","og_image":[{"width":960,"height":593,"url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/biodiversita.jpg","type":"image\/jpeg"}],"author":"ladyitaliaeconomia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ladyitaliaeconomia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/","url":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/","name":"Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio -","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#primaryimage"},"image":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/biodiversita.jpg","datePublished":"2026-04-01T15:27:25+00:00","dateModified":"2026-04-01T15:27:25+00:00","author":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31"},"breadcrumb":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#primaryimage","url":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/biodiversita.jpg","contentUrl":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-content\/uploads\/2019\/06\/biodiversita.jpg","width":960,"height":593},{"@type":"BreadcrumbList","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/tavolo-mimit-cia-agricoltori-in-perdita-per-decine-di-migliaia-di-euro-urgente-credito-dimposta-per-gasolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"Tavolo Mimit: Cia, agricoltori in perdita per decine di migliaia di euro. Urgente credito d\u2019imposta per gasolio"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/909a49cce752523b020fbc37d5ab1c31","name":"ladyitaliaeconomia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cedca10ce7416a579b9fa6bce9c0a8f2?s=96&d=mm&r=g","caption":"ladyitaliaeconomia"},"url":"https:\/\/www.italiaeconomiaonline.it\/web\/author\/ladyitaliaeconomia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7999"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/comments?post=7999"}],"version-history":[{"count":1,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7999\/revisions"}],"predecessor-version":[{"id":8000,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts\/7999\/revisions\/8000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media\/1039"}],"wp:attachment":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/media?parent=7999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/categories?post=7999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags?post=7999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}