{"id":379,"count":6,"description":"","link":"https:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/","name":"agroalimentare","slug":"agroalimentare","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>agroalimentare Archivi - ItaliaEconomiaOnline<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"agroalimentare Archivi - ItaliaEconomiaOnline\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/\" \/>\n<meta property=\"og:site_name\" content=\"ItaliaEconomiaOnline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/\",\"url\":\"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/\",\"name\":\"agroalimentare Archivi - ItaliaEconomiaOnline\",\"isPartOf\":{\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"agroalimentare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.italiaeconomiaonline.it\/web\/#website\",\"url\":\"https:\/\/www.italiaeconomiaonline.it\/web\/\",\"name\":\"ItaliaEconomiaOnline\",\"description\":\"Quotidiano Economico Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"agroalimentare Archivi - ItaliaEconomiaOnline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/","og_locale":"it_IT","og_type":"article","og_title":"agroalimentare Archivi - ItaliaEconomiaOnline","og_url":"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/","og_site_name":"ItaliaEconomiaOnline","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/","url":"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/","name":"agroalimentare Archivi - ItaliaEconomiaOnline","isPartOf":{"@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website"},"breadcrumb":{"@id":"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"http:\/\/www.italiaeconomiaonline.it\/web\/tag\/agroalimentare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.italiaeconomiaonline.it\/web\/"},{"@type":"ListItem","position":2,"name":"agroalimentare"}]},{"@type":"WebSite","@id":"https:\/\/www.italiaeconomiaonline.it\/web\/#website","url":"https:\/\/www.italiaeconomiaonline.it\/web\/","name":"ItaliaEconomiaOnline","description":"Quotidiano Economico Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.italiaeconomiaonline.it\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags\/379"}],"collection":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.italiaeconomiaonline.it\/web\/wp-json\/wp\/v2\/posts?tags=379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}